{"id":8520,"date":"2011-09-22T01:35:13","date_gmt":"2011-09-22T01:35:13","guid":{"rendered":""},"modified":"2011-09-22T01:35:13","modified_gmt":"2011-09-22T01:35:13","slug":"sobre-el-movimiento-de-los-qindignadosq-en-israel","status":"publish","type":"post","link":"https:\/\/litci.org\/es\/sobre-el-movimiento-de-los-qindignadosq-en-israel\/","title":{"rendered":"Sobre el movimiento de los \u00abindignados\u00bb en Israel"},"content":{"rendered":"\n<div>\n\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><img loading=\"lazy\" decoding=\"async\" align=\"left\" alt=\"\" border=\"0\" height=\"136\" hspace=\"6\" src=\"http:\/\/www.litci.org\/es\/wp-content\/uploads\/israel_indignados.jpg\" vspace=\"4\" width=\"204\" \/><\/span><\/span><\/p>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">En las &uacute;ltimas semanas, hubo grandes manifestaciones en Israel. Cerca de 300 mil personas protestaron contra el alto costo de vida y recortes sociales. Hay campamentos de indignados inspirados en los j&oacute;venes espa&ntilde;oles. No demor&oacute; hasta que varias voces comenzasen a declarar que la Revoluci&oacute;n &aacute;rabe o la ola de manifestaciones de Europa hayan llegado a Israel.<\/span><\/span><\/span><\/div>\n<div>\n\t\t<!--more-->\n\t<\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\"><br \/>\n\t\t&ldquo;&iexcl;<i>Como en Egipto! &iexcl;La revoluci&oacute;n a la orden del d&iacute;a en Israel!<\/i>&rdquo; (Alternativa Socialista &ndash; secci&oacute;n rusa del CIO-Militant). Otros dijeron que &ldquo;<i>Los &uacute;ltimos acontecimientos demostraron que la sociedad israel&iacute; puede cambiar de car&aacute;cter<\/i>&rdquo; (El Socialista, de RSD, secci&oacute;n del SU en Rusia) o, incluso, que <i>&ldquo;&rsquo;el verano israel&iacute;&rsquo; puede convertirse en la base de serios cambios dentro de la vida pol&iacute;tica israel&iacute; y el pr&oacute;logo a un acuerdo de paz, entre pueblos que se guerrean hace tanto tiempo<\/i>&rdquo; (El Socialista). En este art&iacute;culo tratamos de explicar por qu&eacute; <b>nuestra opini&oacute;n es diametralmente opuesta<\/b> a la de estas dos organizaciones.<\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><b>&iquest;Qu&eacute; es Israel?<\/b><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><b>&nbsp;<\/b><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\">Para entender por qu&eacute; <b>en Israel no existe ninguna revoluci&oacute;n<\/b> al estilo de las revoluciones &aacute;rabes, y por qu&eacute; &ldquo;<i>la sociedad israelita <b>no<\/b> puede cambiar de car&aacute;cter<\/i>&rdquo;, hay que comprender que Israel no es un estado normal. <span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">Pero, &iquest;ser&aacute; que las cosas son as&iacute;? Opinamos que la ocasi&oacute;n nos da una buena oportunidad de discutir, una vez m&aacute;s, la vieja pol&eacute;mica sobre cu&aacute;l deber&iacute;a ser la pol&iacute;tica de la clase obrera para el Estado sionista.<\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">Israel no es un estado normal, sino un enclave militar, esto es, un puesto avanzado del imperialismo (en especial del norteamericano y brit&aacute;nico), que utiliz&oacute; el dolor del pueblo jud&iacute;o despu&eacute;s del Holocausto para justificar un nuevo crimen contra la humanidad, la expulsi&oacute;n de cientos de miles de &aacute;rabes de la Palestina hist&oacute;rica y la ocupaci&oacute;n militar de su pa&iacute;s y de sus propiedades. <\/span><span>Es un estado artificial, que s&oacute;lo se sustenta gracias al apoyo econ&oacute;mico americano (es el pa&iacute;s del mundo que m&aacute;s ayuda externa recibe), al tr&aacute;fico de armas (4&deg; lugar en el mundo), tr&aacute;fico ilegal de diamantes &ldquo;de sangre&rdquo; (1&deg; lugar en el mundo) y el lavado de dinero de la mafia y de los oligarcas rusos (1&deg; lugar en el mundo). Es un estado militarista, <\/span><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">basado en la guerra permanente contra los &aacute;rabes, y tiene un car&aacute;cter expansionista, racista y religioso. <\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">As&iacute;, se utiliza la opresi&oacute;n contra el pueblo palestino para maximizar las ganancias <\/span><span>de la burgues&iacute;a sionista. Israel, hip&oacute;critamente llamado por los medios de comunicaci&oacute;n de &ldquo;la &uacute;nica democracia del Medio Oriente&rdquo;<\/span><span>, es un Estado basado en el concepto de raza, que trata a una parte de sus habitantes (los &aacute;rabes), como &ldquo;inferiores&rdquo;, &ldquo;no ciudadanos&rdquo;, utilizando m&eacute;todos de guerra civil contra &eacute;stos. O sea, cient&iacute;ficamente hablando, por m&aacute;s duro que pueda parecer, es un Estado nazista, como la Alemania de Hitler o &Aacute;frica del Sur, del r&eacute;gimen del Apartheid.<\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">Por eso, <b>nosotros, en la LIT-CI, nunca reconocemos el derecho a la existencia de este Estado nazi-sionista<\/b>; siempre defendemos la destrucci&oacute;n de Israel y la construcci&oacute;n de una Palestina laica, democr&aacute;tica y no racista, donde palestinos y jud&iacute;os puedan convivir en paz, no como oprimidos y opresores, sino como iguales. Por esa raz&oacute;n, siempre apoyamos la Intifada Palestina. <\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><b>La soluci&oacute;n de los dos estados: una &ldquo;trampa democr&aacute;tica&rdquo; del imperialismo<\/b><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><b>&nbsp;<\/b><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\">La mayor&iacute;a de las corrientes de izquierda, rusas e internacionales, defienden la llamada &ldquo;soluci&oacute;n de los dos estados&rdquo;, o sea, la divisi&oacute;n de la regi&oacute;n en dos partes, dos estados.<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">Aparentemente, una pol&iacute;tica justa, un Estado para los jud&iacute;os y otro para los &aacute;rabes, as&iacute; como hay un Estado para los rusos y otro para los polacos, por ejemplo. Pero, las cosas no son as&iacute;. Todo el territorio de Israel fue robado por la fuerza a los palestinos, obligados a refugiarse en campos en Gaza, Cisjordania o en pa&iacute;ses vecinos. Ellos luchan por su derecho al regreso y recuperar sus casas y ciudades, donde ahora viven los israelitas. No puede haber paz mientras no sea hecha esa justicia hist&oacute;rica, para no hablar del castigo a aquellos que ejecutaron a miles de palestinos mientras los expulsaban. <\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">Adem&aacute;s, Israel es, como decimos m&aacute;s arriba, un puesto militar avanzado del imperialismo, para controlar la estrat&eacute;gica regi&oacute;n del Medio Oriente, donde est&aacute; el 60% de las reservas de petr&oacute;leo del planeta. Israel s&oacute;lo puede existir en tanto cumpla ese objetivo. Por eso, Israel no puede permitir en su entorno la existencia de ning&uacute;n Estado que pueda amenazarlo, menos a&uacute;n un Estado palestino.<\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">Por lo tanto, el tal &ldquo;Estado palestino&rdquo; propuesto en los acuerdos de paz no es y no ser&aacute; un Estado de verdad. Es una farsa total. Ser&iacute;a formado por algunas regiones desconectadas, donde hay concentraci&oacute;n palestina, donde el control a&eacute;reo, mar&iacute;timo y de fronteras ser&iacute;a realizado por Israel &ldquo;para su seguridad&rdquo;. Un Estado en el cual ser&iacute;a vetada la posibilidad de poseer un ej&eacute;rcito. <\/span><span>Adem&aacute;s, m&aacute;s del 60% de los tres millones y medio de palestinos que viven en Cisjordania, Jerusal&eacute;n y en la Faja de Gaza, reciben menos de dos d&oacute;lares diarios, debajo del nivel de pobreza. <\/span><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">En realidad, ser&iacute;a una nueva versi&oacute;n de los<\/span><span> <i><span style=\"background:white\">bantustones <\/span><\/i><sup><span style=\"background:\nwhite;\">1<\/span><\/sup><span style=\"background:white\">, que exist&iacute;an bajo el Apartheid en &Aacute;frica del Sur. O sea, regiones con supuesta autonom&iacute;a negra en un pa&iacute;s racista, dominado por la minor&iacute;a blanca. Ser&iacute;an, en realidad, grandes prisiones a cielo abierto, como eran los ghetos jud&iacute;os en la Europa ocupada por los fascistas. <b>La pol&iacute;tica de los Acuerdos de Paz de Oslo es una gran farsa, destinada a enga&ntilde;ar y derrotar a la Intifada Palestina, la rebeli&oacute;n de su juventud contra la ocupaci&oacute;n.<\/b><\/span><\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">Todos los medios de comunicaci&oacute;n y, lamentablemente, buena parte de la izquierda mundial, tratan de demostrar la cuesti&oacute;n como una lucha entre sectores, de hecho, reaccionarios -como el gobierno de Israel, que no acepta la formaci&oacute;n de un Estado palestino- y sectores democr&aacute;ticos <\/span><span>(&iexcl;como los gobiernos de los pa&iacute;ses imperialistas europeos!)<\/span><span>, que defienden a dicho Estado y los acuerdos de paz. &iexcl;Una gran mentira!<\/span><span>&iexcl;<b>La &ldquo;soluci&oacute;n de los dos estados&rdquo; es la pol&iacute;tica principal del imperialismo y de la gran mayor&iacute;a de los gobiernos del mundo! <\/b><\/span><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">&nbsp;<\/span><span style=\"Times New Roman&quot;;color:#222222;\nbackground:white;\">Pues &eacute;stos perciben que, s&oacute;lo con la fuerza bruta, Israel no est&aacute; consiguiendo detener la lucha palestina. Israel est&aacute; cada d&iacute;a m&aacute;s d&eacute;bil; fue derrotado militarmente en el L&iacute;bano, en el 2006, y hoy est&aacute; cercado por la revoluci&oacute;n &aacute;rabe que derroca a los dictadores aliados de Israel, como Mubarak en Egipto. Cuando la fuerza bruta ya no da resultado, viene la reacci&oacute;n democr&aacute;tica, donde el imperialismo trata, en mesas de negociaci&oacute;n, recuperar lo que perdi&oacute; en la lucha directa.<\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\">Eso es comprendido, incluso, por una parte importante del propio sionismo, como dej&oacute; en claro el anterior primer ministro de Israel, Ehud Olmert: &ldquo;<i>Si llega el d&iacute;a en que la soluci&oacute;n de dos Estados fracasa, y nos vemos obligados a hacer frente a una lucha por la igualdad de derechos al estilo surafricano, el Estado de<\/i> Israel <i>estar&aacute; acabado<\/i>&rdquo;.<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\">Pero, la mejor prueba del car&aacute;cter racista y expansionista de Israel, que demuestra claramente su papel de puesto militar avanzado del imperialismo, es que <span>ni siquiera ese remedo de &ldquo;Estado palestino&rdquo; puede permitirlo, con miedo de que eso sea visto como una conquista de la lucha del pueblo palestino (de hecho, lo ser&iacute;a; Israel jam&aacute;n permitir&iacute;a eso de &ldquo;buena fe&rdquo;), <\/span><span>que dejar&iacute;a claro, a todo el mundo &aacute;rabe, la debilidad de Israel<\/span><span>. Que este remedo de un Estado palestino podr&iacute;a servir como base para el fortalecimiento de la resistencia contra la ocupaci&oacute;n. Esa es la pol&eacute;mica en el seno del imperialismo americano y la mayor&iacute;a de los gobiernos del mundo con el gobierno israel&iacute;. Una diferencia <b>de t&aacute;ctica<\/b> sobre c&oacute;mo mejor someter a la resistencia palestina, con la l&iacute;nea dura del gobierno israel&iacute;, o por medio de una concesi&oacute;n a los palestinos para desviar el eje de su lucha.<\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">Es esa pol&eacute;mica t&aacute;ctica que estar&aacute; presente en la discusi&oacute;n de la ONU en setiembre, sobre el reconocimiento o no del &ldquo;Estado palestino&rdquo;. Todos, de hecho, est&aacute;n a favor de la continuidad de la ocupaci&oacute;n, contra el derecho al retorno de los refugiados palestinos, la recuperaci&oacute;n de sus propiedades, y por la vigencia del car&aacute;cter policial del Estado de Israel, armado hasta los dientes, racista y religioso.<\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><b><span>Las ilusiones de la izquierda<\/span><\/b><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">Lamentablemente, <b>la mayor&iacute;a de la izquierda mundial capitula vergonzosamente a la pol&iacute;tica imperialista<\/b>, as&iacute; como toda la socialdemocracia y corrientes stalinistas. En el campo de la izquierda marxista, las cosas no son mejores. <\/span><span style=\"Times New Roman&quot;;color:#222222;\nbackground:white;\">En el art&iacute;culo citado arriba, del peri&oacute;dico Alternativa Socialista, leemos exactamente lo contrario de lo que nosotros decimos, <\/span><span>que no hay que indisponer a los israelitas contra los &aacute;rabes, que no hay razones para incentivar divisiones raciales y de credo entre ellos. Defienden que es necesario unir a los trabajadores &aacute;rabes y jud&iacute;os para luchar juntos contra sus respectivas burgues&iacute;as,<\/span><span>y por la reorganizaci&oacute;n econ&oacute;mica socialista de su econom&iacute;a, y que &ldquo;<i>la cuesti&oacute;n de las formas que vaya a asumir el nuevo estado o estados, al final, ser&aacute; decidida democr&aacute;ticamente por los propios &aacute;rabes y jud&iacute;os del Medio Oriente Socialista, donde a todos se les garantizar&aacute;n plenamente los derechos nacionales<\/i>&rdquo;. <\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">Lamentablemente, ese bello escenario id&iacute;lico s&oacute;lo existe en la cabeza de los dirigentes del CIO, pues <b>justamente para que pueda haber <\/b><\/span><span>una discusi&oacute;n democr&aacute;tica y soberana de los trabajadores del Medio Oriente, antes que nada, hay que destruir al Estado de Israel, que impide cualquier democracia y soberan&iacute;a para el pueblo palestino. <\/span><b><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">&iexcl;El &uacute;nico camino para un Medio Oriente Socialista pasa por la destrucci&oacute;n de Israel!<\/span><\/b><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">Y as&iacute; como el Estado sionista no es un Estado normal, sino un enclave militar, tampoco lo es la clase obrera que vive all&iacute;. Al ser Israel un Estado artificial, basado en el robo y la superexplotaci&oacute;n de los palestinos, la clase obrera jud&iacute;a en Israel <b>es, tambi&eacute;n, parte de la ocupaci&oacute;n. <\/b>Recibe privilegios de la ocupaci&oacute;n. Tiene un nivel de vida mejor del de los trabajadores &aacute;rabes, exactamente porque recibe migajas derivadas de la explotaci&oacute;n de &eacute;stos, y por los fondos que Israel recibe de EE.UU.<\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">Ninguna clase obrera en el mundo, como ya dec&iacute;a Marx, lucha para empeorar su nivel de vida o para perder sus privilegios. <b>Por eso, la clase obrera israelita no es (y no ser&aacute;) revolucionaria, ni siquiera reformista<\/b>. Es, intr&iacute;nsecamente, reaccionaria. Su bienestar depende de la continuidad y de la ampliaci&oacute;n de la ocupaci&oacute;n del territorio palestino, de su car&aacute;cter de Estado policial. No se puede esperar de los trabajadores jud&iacute;os un cambio de car&aacute;cter del Estado sionista, para que &eacute;ste deje de ser sionista, racista y expansionista. <\/span><span style=\"Times New Roman&quot;;color:#222222;\nbackground:white;\">Por eso, al contrario de lo que dice RSD, &ldquo;l<i>a sociedad israelita <b>no<\/b> puede cambiar de car&aacute;cter<\/i>&rdquo;. <\/span><span>Israel no puede ser reformado, s&oacute;lo puede ser destruido.<\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">Se puede esperar que algunos trabajadores e intelectuales, individualmente, lleguen a la comprensi&oacute;n del rol de Israel en la regi&oacute;n, pero como clase, no se puede esperar nada. Ese cambio s&oacute;lo puede venir por medio del pueblo palestino, apoyado por el conjunto de los pueblos &aacute;rabes y con la simpat&iacute;a de la clase obrera mundial, con la destrucci&oacute;n de Israel. Y la clase obrera israelita no ser&aacute; una aliada en esa lucha, ser&aacute; una aliada de la burgues&iacute;a israelita y del imperialismo para tratar de aplastar a la lucha palestina.<\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><b>Las recientes movilizaciones en Israel<\/b><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">Pero, &iquest;ser&aacute; que las movilizaciones recientes en Israel niegan todo eso? &iquest;Ser&aacute; que muestran que, a pesar de toda nuestra teor&iacute;a, la clase obrera israelita puede, sin superar sus debilidades, cumplir un papel progresivo?<\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">Las manifestaciones en Israel, de hecho, fueron muy grandes, tal vez las mayores desde la fundaci&oacute;n del Estado. Son manifestaciones contra la degradaci&oacute;n del nivel de vida de los israelitas, el aumento de los precios de vivienda y contra los recortes en el presupuesto social<\/span><span style=\"Times New Roman&quot;;color:#222222;\nbackground:white;\">. Los recortes de gastos para salud y educaci&oacute;n est&aacute;n relacionados al aumento del presupuesto militar (m&aacute;s del 30% del presupuesto general, relativamente el mayor del mundo), y los aumentos de los costos de vivienda (en los &uacute;ltimos seis a&ntilde;os el alquiler de una vivienda ha subido el 250% en Tel Aviv, frente al 1% de incremento salarial) con las dificultades de profundizar la ocupaci&oacute;n lo que, otra vez, revela m&aacute;s el car&aacute;cter militarista y expansionista del estado israel&iacute;. Pero, en tales manifestaciones por la &ldquo;justicia social&rdquo; no se pronunci&oacute; ni una palabra sobre la ocupaci&oacute;n.<\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\">&ldquo;<i>Vemos a la ocupaci&oacute;n como un tema de seguridad que no est&aacute; relacionado con nuestra causa por la justicia social<\/i>&rdquo;, dijo Hadas Kouchalevich, dirigente de la Uni&oacute;n de Estudiantes de Israel. En la medida que crece el movimiento, se hace m&aacute;s inclusivo, pero no de palestinos (como quiere hacernos creer el art&iacute;culo de Alternativa Socialista). En su lugar, colonos jud&iacute;os son ahora bienvenidos a la protesta. El gran asentamiento de Ariel es un ejemplo: fue construido sobre cientos de hect&aacute;reas de tierra confiscada a los palestinos y rodeado por el muro de separaci&oacute;n israel&iacute;, que crea una cu&ntilde;a entre siete aldeas palestinas cercanas. Ariel est&aacute; construido directamente sobre uno de los mayores acu&iacute;feros de la regi&oacute;n. En agosto de este a&ntilde;o, el gobierno israel&iacute; aprob&oacute; la construcci&oacute;n de 277 nuevas viviendas en Ariel. El 13 de agosto, cuando los dirigentes de la protesta declararon una &ldquo;expansi&oacute;n hacia la periferia&rdquo; de Israel, Ariel realiz&oacute; su primera manifestaci&oacute;n por la justicia social, en la que cientos de residentes descontentos exigieron precios m&aacute;s bajos de las viviendas. El movimiento de los indignados apoy&oacute; la protesta en Ariel.<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\">Adem&aacute;s, los principales rabinos del nacionalismo religioso y figuras destacadas de la ultraderecha han puesto sobre la mesa su soluci&oacute;n a la carest&iacute;a de los pisos: levantarlos sobre el territorio ocupado de los palestinos. &laquo;<i>Gracias a que hay 350.000 personas que viven en Judea y Samaria <\/i>(nombres b&iacute;blicos con los que los sionistas denominan a Cisjordania)<i> los precios de las casas en Israel son m&aacute;s bajos<\/i>&raquo;, advierte Roni Arzi, portavoz del consejo de colonos Yesha. Seg&uacute;n &eacute;l, uno de los problemas que est&aacute; detr&aacute;s de la subida de los precios es que &laquo;<i>el Gobierno ha paralizado, en los dos &uacute;ltimos a&ntilde;os, la concesi&oacute;n de nuevas licencias de construcci&oacute;n<\/i>&raquo; en Cisjordania.<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\">Sin embargo, desde que se iniciaron los campamentos de indignados en las principales ciudades del pa&iacute;s, el gobierno israel&iacute; ha hecho dos anuncios de aprobaci&oacute;n de nuevas viviendas en territorios palestinos. El Comit&eacute; de Planificaci&oacute;n del Ministerio del Interior dio luz verde, hace una semana, para la edificaci&oacute;n de 930 casas en la colonia jud&iacute;a de Har Homa, ubicada cerca de Bel&eacute;n, como una medida que el ministro de Interior, Eli Yishai, vincul&oacute; directamente a las protestas sociales.<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">O sea, el aumento de precios de las viviendas es producto de la especulaci&oacute;n, pues no hay viviendas ni tierras suficientes para todos y, <b>la &uacute;nica salida para bajar los precios, sin alterar el car&aacute;cter del Estado sionista, es ampliar la ocupaci&oacute;n<\/b>. Eso significa que, o la lucha de los trabajadores israel&iacute;s se dirigir&aacute; contra el Estado sionista<\/span><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">, i.e., por su destrucci&oacute;n (lo que, como vimos arriba, es imposible),<\/span><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\"> o se convertir&aacute;, m&aacute;s temprano que tarde, en una lucha reaccionaria para profundizar la colonizaci&oacute;n de las tierras palestinas -lo que ya es agitado por las corrientes m&aacute;s derechistas en Israel en los campamentos de los &ldquo;indignados&rdquo;. <\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><b>Israel y la revoluci&oacute;n &aacute;rabe<\/b><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><b>&nbsp;<\/b><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\">Hay, de hecho, una relaci&oacute;n muy profunda entre la lucha de los &ldquo;indignados&rdquo; israel&iacute;s y la revoluci&oacute;n &aacute;rabe, pero no la que ven las corrientes arriba citadas. <b><span>La revoluci&oacute;n &aacute;rabe es la culminaci&oacute;n de un proceso que ya viene de varios a&ntilde;os de debilitamiento del otrora &ldquo;invencible&rdquo; Estado sionista<\/span><\/b><span>. Las dos Intifadas palestinas, la derrota en el sur del L&iacute;bano<\/span>, la dif&iacute;cil situaci&oacute;n de EE.UU. en Irak y Afganist&aacute;n, la derrota de Bush y su &ldquo;Guerra contra el terror&rdquo; y, ahora, la revoluci&oacute;n &aacute;rabe que sacude toda la estabilidad de la regi&oacute;n, derrocando a los principales dictadores-aliados de Israel como era Mubarak, est&aacute;n dejando a Israel en una posici&oacute;n cada vez m&aacute;s aislada, vulnerable e insostenible.<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;background:white;\">La reacci&oacute;n de los &ldquo;indignados&rdquo; israel&iacute;es muestra que se abrir&aacute;n graves fisuras en el campo enemigo, que la base social de apoyo al gobierno israelita y de su pol&iacute;tica est&aacute;n en crisis. Eso es positivo y contribuye para debilitar a&uacute;n m&aacute;s a Israel y en fortalecer la resistencia palestina. Pero, como ese &ldquo;indignados&rdquo; est&aacute;n limitados por un obst&aacute;culo objetivo &ndash;el hecho de ser parte de la ocupaci&oacute;n- &nbsp;no podr&aacute;n ir muy lejos. Bastar&aacute; con percibir que su lucha lleva al debilitamiento del Estado sionista y al fortalecimiento de la resistencia palestina, para girar a apoyar a su burgues&iacute;a en nombre de la &ldquo;seguridad nacional&rdquo;. <\/span><\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><br \/>\n\t\t<\/span><\/span><\/div>\n<div>\n\t\t<span style=\"font-size:14px;\"><span style=\"font-family:georgia, serif;\"><span style=\"Times New Roman&quot;;\ncolor:#222222;\">Traducci&oacute;n:&nbsp;<b>Laura S&aacute;nchez<\/b><\/span><\/span><\/span><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En las &uacute;ltimas semanas, hubo grandes manifestaciones en Israel. Cerca de 300 mil personas protestaron contra el alto costo de vida y recortes sociales. Hay campamentos de indignados inspirados en los j&oacute;venes espa&ntilde;oles. No demor&oacute; hasta que varias voces comenzasen a declarar que la Revoluci&oacute;n &aacute;rabe o la ola de manifestaciones de Europa hayan llegado [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":18609,"menu_order":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"litci_post_political_author":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-8520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"fimg_url":"https:\/\/litci.org\/es\/wp-content\/uploads\/israel_indignados.jpg","categories_names":[],"author_info":{"name":"Kely","pic":"https:\/\/secure.gravatar.com\/avatar\/19003bf6219614b90207b39bd4a2733ce9cf96693efdfd639b15a829beed53d1?s=96&d=mm&r=g"},"political_author":null,"tagline":"","_links":{"self":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/8520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/comments?post=8520"}],"version-history":[{"count":0,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/8520\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media\/18609"}],"wp:attachment":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media?parent=8520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/categories?post=8520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/tags?post=8520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}