{"id":80381,"date":"2025-08-16T11:39:52","date_gmt":"2025-08-16T11:39:52","guid":{"rendered":"https:\/\/litci.org\/es\/?p=80381"},"modified":"2025-08-27T23:11:57","modified_gmt":"2025-08-27T23:11:57","slug":"sobre-el-sectarismo-el-oportunismo-y-las-relaciones-con-el-gobierno-de-lula-en-la-lucha-contra-trump","status":"publish","type":"post","link":"https:\/\/litci.org\/es\/sobre-el-sectarismo-el-oportunismo-y-las-relaciones-con-el-gobierno-de-lula-en-la-lucha-contra-trump\/","title":{"rendered":"Sobre el sectarismo, el oportunismo y las relaciones con el gobierno de Lula en la lucha contra Trump"},"content":{"rendered":"\n<p>Por Marichua Fontana (Partido Socialista de los Trabajadores Unificado &#8211; Brasil)<\/p>\n\n\n\n<p>Los revolucionarios y la clase trabajadora deben colocarse a la vanguardia de la lucha contra el ataque de Trump-Bolsonaro (es decir, el imperialismo estadounidense) contra Brasil, un pa\u00eds semicolonial.<\/p>\n\n\n\n<p>No es casualidad que el PSTU y el Sindicato de Metal\u00fargicos de S\u00e3o Jos\u00e9 dos Campos y Regi\u00f3n, liderados principalmente por militantes del partido, asumieran el liderazgo en la defensa de la soberan\u00eda del pa\u00eds, realizando asambleas masivas en las f\u00e1bricas para discutir la cuesti\u00f3n y tomando la iniciativa de llamar a todas las organizaciones de trabajadores a organizar una manifestaci\u00f3n contra los ataques.<\/p>\n\n\n\n<p>En esta lucha, debemos estar dispuestos a unirnos en la acci\u00f3n con todos los que est\u00e9n dispuestos a enfrentar el ataque, incluido el gobierno de Lula y cualquier otro que quiera participar.<\/p>\n\n\n\n<p>Pero tambi\u00e9n en esta batalla es necesario mantener un principio: la clase obrera y los revolucionarios deben tener independencia pol\u00edtica y organizativa frente a la burgues\u00eda y, por tanto, tambi\u00e9n frente al gobierno de conciliaci\u00f3n de clases de Lula que, en este momento, representa el grueso de la burgues\u00eda.<\/p>\n\n\n\n<p>Por lo tanto, no dejaremos de ser una oposici\u00f3n de izquierda y socialista al gobierno, sino que lucharemos juntos contra el imperialismo si este toma medidas efectivas para enfrentarlo. Asimismo, defenderemos las posibles medidas contra los imperialistas.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">La subordinaci\u00f3n del pa\u00eds al imperialismo y la eterna cobard\u00eda de la burgues\u00eda brasile\u00f1a<\/h5>\n\n\n\n<p>Hay que decir, sin embargo, que, m\u00e1s all\u00e1 de defender la no interferencia de Trump en el juicio a Bolsonaro por el Supremo Tribunal Federal (STF), hasta ahora el gobierno no ha tomado ninguna medida, m\u00e1s all\u00e1 de las palabras, contra los ataques de Trump, particularmente lo que se llama un ataque econ\u00f3mico y que, de hecho, no es m\u00e1s que \u00abecon\u00f3mico y pol\u00edtico\u00bb.<\/p>\n\n\n\n<p>Por ejemplo, con una gorra azul con la leyenda \u201cBrasil pertenece a los brasile\u00f1os\u201d, en contraste con el lema \u201cMake America Great Again\u201d usado por los partidarios de Trump y Bolsonaro, Lula lleg\u00f3 a decir que \u201clas tierras raras son nuestras\u201d, que no renunciar\u00eda a gravar a las \u201cBig Tech\u201d y que podr\u00eda utilizar la Ley de Reciprocidad.<\/p>\n\n\n\n<p>Pero, mientras tanto, el vicepresidente Geraldo Alckmin, los ministros Haddad y Simone Tebet y la mayor parte de la comunidad empresarial est\u00e1n proponiendo negociaciones tanto con las tierras raras como con las grandes tecnol\u00f3gicas.<\/p>\n\n\n\n<p>Al mismo tiempo, mientras algunas empresas anuncian despidos, otras piden asistencia gubernamental para, en efecto, avanzar a\u00fan m\u00e1s en la desregulaci\u00f3n laboral y, tambi\u00e9n, mantener empleos, reducir salarios y exigir al gobierno que pague los salarios reducidos a los trabajadores.<\/p>\n\n\n\n<p>Sabemos que Brasil, que deber\u00eda pertenecer a los brasile\u00f1os, lamentablemente no es as\u00ed. La clase dominante es un socio minoritario en la explotaci\u00f3n de Brasil por diversas potencias imperialistas y, cada d\u00eda que pasa, subordina a\u00fan m\u00e1s al pa\u00eds. Esta actitud siempre ha sido apoyada por los gobiernos en el poder, incluyendo los del Partido de los Trabajadores (PT), que siempre han gobernado el pa\u00eds dentro de los l\u00edmites de esta subordinaci\u00f3n, seg\u00fan los intereses de las multinacionales y los pa\u00edses imperialistas, e incluso la han profundizado, al ser gobiernos proimperialistas.<\/p>\n\n\n\n<p>Esto no significa que, dada la magnitud del ataque actual, la burgues\u00eda y el gobierno no puedan verse obligados a reaccionar en cierta medida. Sin embargo, no podemos olvidar que la lucha contra el imperialismo y por la soberan\u00eda es nuestra lucha, la de la clase obrera, y debemos ponernos al frente de esta batalla.<\/p>\n\n\n\n<p>Si el gobierno y la burgues\u00eda nacional, que manejan aqu\u00ed cotidianamente los intereses de las multinacionales y del sistema financiero internacional, toman una posici\u00f3n para enfrentar y reaccionar a este ataque, estaremos dispuestos a actuar en unidad en tal lucha, pero sin perder nuestra independencia pol\u00edtica y organizativa.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Contenido y forma, estrategia y t\u00e1ctica<\/h5>\n\n\n\n<p>En una situaci\u00f3n como esta, el contenido (o la esencia) de nuestra pol\u00edtica hacia el imperialismo o el gobierno colaboracionista del Partido de los Trabajadores con la burgues\u00eda no cambia; pero s\u00ed cambia nuestra forma de abordarlo. En otras palabras, no cambia nuestra estrategia; cambia nuestra t\u00e1ctica.<\/p>\n\n\n\n<p>Exigimos que Lula comience a implementar efectivamente la reciprocidad. Si lo hace, nos uniremos en nuestros esfuerzos para combatir y enfrentar al imperialismo. Aun as\u00ed, mantendremos plena independencia pol\u00edtica y denunciaremos y confrontaremos cualquier limitaci\u00f3n impuesta por el gobierno burgu\u00e9s y colaboracionista de clase de Lula en esta lucha. Es decir, si la confrontaci\u00f3n realmente se concreta.<\/p>\n\n\n\n<p>Seguiremos sin apoyar pol\u00edticamente al gobierno porque, en primer lugar, nuestra estrategia sigue siendo construir la independencia de clase. Adem\u00e1s, la lucha real, o incluso definitiva, por la soberan\u00eda nacional no puede librarse dentro de los l\u00edmites del Marco Fiscal, en alianza con la burgues\u00eda y dentro de los l\u00edmites de este sistema.<\/p>\n\n\n\n<p>La soberan\u00eda s\u00f3lo se puede lograr mediante la lucha de la clase obrera y sus aliados, del campo y de la ciudad, incluidos los peque\u00f1os productores, y mediante un gobierno de los trabajadores y sus aliados (tambi\u00e9n en el campo y la ciudad), sin la burgues\u00eda, comprometido con un proyecto socialista de sociedad.<\/p>\n\n\n\n<p>Por eso, estando dispuestos a hacer un golpe junto al gobierno contra el imperialismo, si \u00e9ste lo hace, continuaremos en la oposici\u00f3n de izquierda y socialista al gobierno.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Sectarios y oportunistas<\/h5>\n\n\n\n<p>En su libro \u201cGobiernos de Frente Popular en la Historia\u201d, el trotskista argentino Nahuel Moreno utiliza una definici\u00f3n de Trotsky que destaca que tanto los sectarios como los oportunistas est\u00e1n unidos por el mismo m\u00e9todo:<\/p>\n\n\n\n<p>\u201c&nbsp;<em>El pensamiento oportunista, como el pensamiento sectario, tiene caracter\u00edsticas en com\u00fan: de la complejidad de las circunstancias y fuerzas, extraen uno o dos factores que les parecen los m\u00e1s importantes \u2013y que, de hecho, a veces lo son\u2013 y a\u00edslan estos factores de la compleja realidad, atribuy\u00e9ndoles un poder sin l\u00edmites ni restricciones<\/em>&nbsp;\u201d, escribi\u00f3.<\/p>\n\n\n\n<p>\u00bb&nbsp;<em>El choque entre sectarismo y oportunismo surge, desde un punto de vista metodol\u00f3gico, del hecho de que el elemento que uno absolutiza es el opuesto de lo que el otro absolutiza. Ninguno de los dos presta atenci\u00f3n a que ambos elementos son parte de la realidad<\/em>&nbsp;\u00ab, concluy\u00f3.<\/p>\n\n\n\n<p>Para ilustrar lo que Trotsky y Moreno discutieron, veamos algunos ejemplos de c\u00f3mo se comportan los sectarios y oportunistas en la lucha de clases.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Sectarismo<\/h5>\n\n\n\n<p>Ante un ataque imperialista o una invasi\u00f3n militar imperialista, en el caso de un golpe militar bonapartista o del ascenso del fascismo, el sectario se niega a considerar la \u201cforma\u201d de tratar con este gobierno (es decir, la t\u00e1ctica) e incluso se niega a adaptar la suya propia.<\/p>\n\n\n\n<p>Una postura sectaria que puede llegar hasta la traici\u00f3n, como demostr\u00f3 Trotsky en relaci\u00f3n a la posici\u00f3n ultraizquierdista adoptada por el estalinismo, que, tras el ascenso de Hitler, equipar\u00f3 la socialdemocracia al nazismo y se neg\u00f3 a atacar junto con \u00e9ste a los nazis.<\/p>\n\n\n\n<p>En situaciones como estas, los sectarios y ultraizquierdistas se niegan a luchar junto al gobierno contra la reacci\u00f3n. El sectario, dice Moreno, se niega a adaptar sus consignas y lenguaje, pisoteando las ilusiones y creencias de las masas. En definitiva, expresa un desprecio peque\u00f1oburgu\u00e9s por las aspiraciones de los trabajadores.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Oportunismo o la \u201cizquierda del orden\u201d<\/h5>\n\n\n\n<p>Pero tanto para Trotsky como para Moreno, frente a un gobierno de colaboraci\u00f3n de clases, el oportunismo es el principal problema, incluso en una situaci\u00f3n de ataque imperialista, invasi\u00f3n o golpe militar.<\/p>\n\n\n\n<p>En los \u00faltimos d\u00edas, hemos vivido tres momentos distintos en la situaci\u00f3n econ\u00f3mica del pa\u00eds. En el primero, el gobierno de Lula se vio acorralado por el Centr\u00e3o, que derog\u00f3 el IOF (Impuesto Indirecto) y cuestion\u00f3 las finanzas p\u00fablicas, limitadas por el Marco Fiscal neoliberal.<\/p>\n\n\n\n<p>En el segundo momento, el Planalto, el Frente Brasil Popular (FBP) y el Frente Povo Sem Medo (FPSM), con toda la izquierda que apoya al gobierno, lideraron una reacci\u00f3n, de hecho en defensa del gobierno y de todas sus pol\u00edticas, supuestamente contra el \u201cCongreso enemigo del pueblo\u201d, o mejor dicho, contra el Centr\u00e3o.<\/p>\n\n\n\n<p>Salieron en defensa de la exenci\u00f3n del Impuesto sobre la Renta para quien gana hasta R$ 5 mil, exigiendo el fin de la escala 6&#215;1 y la tributaci\u00f3n de los BBBs (multimillonarios, apuestas y bancos), pero sin cuestionar la pol\u00edtica econ\u00f3mica del gobierno de Lula y el ajuste fiscal, principal motivo del IOF (que adem\u00e1s de ser un impuesto indirecto, ten\u00eda como objetivo pagar los intereses de la deuda a los banqueros).<\/p>\n\n\n\n<p>Por supuesto, al mismo tiempo, busc\u00f3 viabilizar las cuentas del gobierno y hacer algunas concesiones (de cara a las elecciones de 2026), adem\u00e1s de mantener los dem\u00e1s ataques que requiere esta pol\u00edtica econ\u00f3mica.<\/p>\n\n\n\n<p>Es decir, sin cuestionar el ajuste fiscal y en defensa del gobierno, con su pol\u00edtica econ\u00f3mica y todo lo dem\u00e1s, se lanz\u00f3 una \u00abmovilizaci\u00f3n\u00bb que, en realidad, tiene el objetivo de salir a las calles para una campa\u00f1a electoral, a favor de \u00abLula 2026\u00bb, y no hacer que la clase avance efectivamente en sus luchas y reivindicaciones, que exigen romper con la actual pol\u00edtica econ\u00f3mica.<\/p>\n\n\n\n<p>Ahora, el imperialismo ataca. Y, una vez m\u00e1s, la lucha es por derrotarlo y por la unidad de acci\u00f3n necesaria para enfrentarlo, manteniendo la independencia pol\u00edtica y organizativa de la clase obrera.<\/p>\n\n\n\n<p>Sin embargo, una vez m\u00e1s, cierta \u201cizquierda del orden\u201d sigue incinerando la independencia de la clase trabajadora y, tambi\u00e9n, el necesario enfrentamiento, de verdad, con los imperialismos, en el altar del apoyo pol\u00edtico al gobierno y de una agenda subordinada a otra campa\u00f1a electoral, la de 2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Marichua Fontana (Partido Socialista de los Trabajadores Unificado &#8211; Brasil) Los revolucionarios y la clase trabajadora deben colocarse a la vanguardia de la lucha contra el ataque de Trump-Bolsonaro (es decir, el imperialismo estadounidense) contra Brasil, un pa\u00eds semicolonial. No es casualidad que el PSTU y el Sindicato de Metal\u00fargicos de S\u00e3o Jos\u00e9 dos [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":80382,"menu_order":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"litci_post_political_author":"PSTU - Brasil","footnotes":""},"categories":[2676,2653],"tags":[18360,2836,13727],"class_list":["post-80381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-pstu-brasil","tag-aranceles","tag-brasil-2","tag-tarifazo"],"fimg_url":"https:\/\/litci.org\/es\/wp-content\/uploads\/2025\/08\/trum_sindmetal-1-1.jpg","categories_names":["Brasil","PSTU - Brasil"],"author_info":{"name":"leonardo","pic":"https:\/\/secure.gravatar.com\/avatar\/5b026831a33fc9397b874aaf2fbce7cc661697946383efa447f6bf2fd4c79d48?s=96&d=mm&r=g"},"political_author":"PSTU - Brasil","tagline":"","_links":{"self":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/80381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/comments?post=80381"}],"version-history":[{"count":1,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/80381\/revisions"}],"predecessor-version":[{"id":80383,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/80381\/revisions\/80383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media\/80382"}],"wp:attachment":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media?parent=80381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/categories?post=80381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/tags?post=80381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}