{"id":67894,"date":"2021-12-09T12:41:44","date_gmt":"2021-12-09T12:41:44","guid":{"rendered":"https:\/\/litci.org\/es\/?p=67894"},"modified":"2024-11-03T13:27:54","modified_gmt":"2024-11-03T13:27:54","slug":"un-recorrido-por-la-historia-de-la-ex-urss","status":"publish","type":"post","link":"https:\/\/litci.org\/es\/un-recorrido-por-la-historia-de-la-ex-urss\/","title":{"rendered":"Un recorrido por la historia de la ex URSS"},"content":{"rendered":"<p><em>Actualmente existen muchos debates entre el activismo que lucha en escala internacional, especialmente sobre c\u00f3mo enfrentar las crisis que impone el capitalismo. Llevamos casi dos a\u00f1os de una pandemia que est\u00e1 muy lejos de ser controlada y que demostr\u00f3, una vez m\u00e1s, que quienes m\u00e1s sufren sus consecuencias son los pa\u00edses pobres y la clase trabajadora mundial.<\/em><!--more--><\/p>\n<p>Estamos ante la posibilidad de un colapso ambiental, donde la vida en el planeta est\u00e1 amenazada. Esto es producto de la anarqu\u00eda de la producci\u00f3n capitalista, que mantiene una relaci\u00f3n destructiva con la naturaleza. A eso hay que sumarle la gran desigualdad social, en la que unos pocos magnates controlan casi toda la riqueza mientras los pueblos son condenados a p\u00e9simos sistemas de sanidad, condiciones laborales precarias y hasta pr\u00e1cticas esclavistas.<\/p>\n<p>Ante esta crisis permanente del sistema capitalista vemos centenares de procesos de lucha: contra el racismo en Estados Unidos; contra el machismo, con millones de mujeres en las calles; contra el saqueo imperialista de los recursos, y por la defensa del medio ambiente. En todo el mundo explotan huelgas, e incluso vemos resistencia armada y revoluciones que derriban dictaduras. Pero todav\u00eda estamos lejos de concretar una alternativa n\u00edtida, por la positiva, contra el capitalismo. La gran mayor\u00eda del activismo se declara anticapitalista, rechaza las transnacionales, repudia a los banqueros, exige el fin de la destrucci\u00f3n del medio ambiente. Pero no se ha logrado destruir el capitalismo y, as\u00ed, en los \u00faltimos 30 a\u00f1os han empeorado todos los problemas econ\u00f3micos, sociales, pol\u00edticos.<\/p>\n<p>Desde la LIT tenemos conciencia de que no basta solo luchar. Debemos construir un proyecto revolucionario, socialista, y oponerlo al sistema capitalista. Un proyecto que destruya este sistema desde la ra\u00edz y pueda construir una sociedad donde la econom\u00eda y la pol\u00edtica est\u00e9n al servicio de satisfacer la necesitades de la especie humana en una relaci\u00f3n arm\u00f3nica con la naturaleza. Pero, para avanzar en ese proyecto nos parece que uno de los caminos es cuestionar la invencibilidad del capitalismo.<\/p>\n<p>Nos parece que el activismo social y la militancia de izquierda deben estudiar las experiencias de lucha y las revoluciones, tanto las triunfantes como las derrotadas. Ese estudio encierra valiosas lecciones para comprender mejor el presente, no repetir errores, y estar m\u00e1s fuertes en el combate contra el capitalismo. Nos parece muy importante que estudiemos a fondo c\u00f3mo funcionaron las sociedades que intentaron construir un modelo alternativo al capitalismo, como fue el caso del proceso que se inici\u00f3 con la Revoluci\u00f3n Rusa de 1917. Hay que estudiar c\u00f3mo aquellas surgieron, cu\u00e1les fueron sus instituciones, sus bases econ\u00f3micas, y los motivos de su destrucci\u00f3n.<\/p>\n<div id=\"attachment_67985\" style=\"width: 810px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-67985\" class=\"size-full wp-image-67985\" src=\"https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/AP-Muro-de-Berlin-1.jpg\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/AP-Muro-de-Berlin-1.jpg 800w, https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/AP-Muro-de-Berlin-1-300x169.jpg 300w, https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/AP-Muro-de-Berlin-1-768x432.jpg 768w, https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/AP-Muro-de-Berlin-1-747x420.jpg 747w, https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/AP-Muro-de-Berlin-1-640x360.jpg 640w, https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/AP-Muro-de-Berlin-1-681x383.jpg 681w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><p id=\"caption-attachment-67985\" class=\"wp-caption-text\">Ca\u00edda del Muro de Berl\u00edn 1989.<\/p><\/div>\n<p>Queremos invitar al activismo que est\u00e1 en medio de procesos de lucha a que se acerque a conocer, desde una mirada marxista, es decir, totalmente cr\u00edtica de la historia oficial, el surgimiento, la degeneraci\u00f3n y la ca\u00edda de la URSS y de los ex Estados obreros. Sin ese estudio, sin ese balance hist\u00f3rico a la luz de la experiencia posterior, estamos convencidos de que no es posible encarar los desaf\u00edos de nuevas revoluciones socialistas.<\/p>\n<p>Las \u00faltimas tres d\u00e9cadas estuvieron marcadas por una propaganda sistem\u00e1tica de los Estados, las transnacionales de la comunicaci\u00f3n y los partidos pol\u00edticos burgueses, en la que se repite que el socialismo no es viable, que \u201cfracas\u00f3\u201d hace 30 a\u00f1os y que qued\u00f3 relegado al basurero de la historia. Una de las falacias m\u00e1s comunes de esta campa\u00f1a es sostener que Stalin y la burocracia que gobern\u00f3 la URSS desde 1924 ser\u00edan una \u201ccontinuidad\u201d de la obra y del legado militante de Marx, Engels, Rosa Luxemburgo, Lenin y Trotsky. Gastan miles de p\u00e1ginas y horas de videos para afirmar que la falta de democracia dentro de los ex Estados obreros fue una consecuencia inevitable de la doctrina comunista. Tambi\u00e9n argumentan que, entre 1988 y 1991, las masas de esos Estados salieron a las calles para exigir el \u201cfin del comunismo\u201d y la vuelta al sistema capitalista.<\/p>\n<p><a href=\"https:\/\/litci.org\/es\/30-anos-disolucion-de-la-urss\/\">Este especial presenta a las y los lectores una selecci\u00f3n de textos especialmente escritos para discutir el trig\u00e9simo aniversario de la disoluci\u00f3n de la URSS<\/a>, adem\u00e1s de otras herramientas, como videos y materiales de archivo, a trav\u00e9s de los cuales queremos, a luz de conceptos muy precisos, hacer un recorrido por la historia de la ex URSS y explicar c\u00f3mo se fue degenerando.<\/p>\n<p>A partir de los textos que se ir\u00e1n publicando en los pr\u00f3ximos 30 d\u00edas, intentaremos explicar primero qu\u00e9 fue el proyecto de la Perestroika y c\u00f3mo la restauraci\u00f3n capitalista fue hecha por la propia burocracia estalinista mucho antes de que las masas salieran a luchar contra la miseria a que hab\u00edan sido llevadas. A partir de ah\u00ed, haremos una detallada explicaci\u00f3n de lo que fue la burocracia estalinista, c\u00f3mo surgi\u00f3 y c\u00f3mo cambi\u00f3 el r\u00e9gimen de democracia obrera que hab\u00eda existido hasta la muerte de Lenin.<\/p>\n<p>Haremos un recorrido sobre las implicancias de la doctrina del socialismo en un solo pa\u00eds, la mayor ruptura con el marxismo llevada adelante por Stalin y su camarilla, y veremos todas las repercusiones que esto tuvo en los procesos revolucionarios y en la Segunda Guerra Mundial.<\/p>\n<p>Explicaremos por qu\u00e9, en los primeros a\u00f1os de la URSS s\u00ed hubo un r\u00e9gimen de democracia obrera, en el que se dieron importantes conquistas sociales y democr\u00e1ticas; mostraremos c\u00f3mo hasta 1924 el Estado Obrero estaba al servicio de la revoluci\u00f3n mundial, d\u00e1ndole total prioridad a la construcci\u00f3n de la Tercera Internacional, que luego ser\u00eda liquidada por la burocracia estalinista.<\/p>\n<div id=\"attachment_67987\" style=\"width: 990px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-67987\" class=\"size-full wp-image-67987\" src=\"https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/Moscu.Comunismo.1917.jpg\" alt=\"\" width=\"980\" height=\"659\" srcset=\"https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/Moscu.Comunismo.1917.jpg 980w, https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/Moscu.Comunismo.1917-300x202.jpg 300w, https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/Moscu.Comunismo.1917-768x516.jpg 768w, https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/Moscu.Comunismo.1917-625x420.jpg 625w, https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/Moscu.Comunismo.1917-537x360.jpg 537w, https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/Moscu.Comunismo.1917-640x430.jpg 640w, https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/Moscu.Comunismo.1917-681x458.jpg 681w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/><p id=\"caption-attachment-67987\" class=\"wp-caption-text\">1917: Soldados marchan en Mosc\u00fa con una manta que dice -comunismo-<\/p><\/div>\n<p>Por otra parte, es muy importante mostrar la resistencia de las masas a esta burocracia. En ese sentido, analizaremos los procesos de revoluci\u00f3n pol\u00edtica, antiburocr\u00e1ticos, en los pa\u00edses del glacis sovi\u00e9tico: Alemania Oriental, Hungr\u00eda, Checoslovaquia y Polonia. Tambi\u00e9n explicaremos en qu\u00e9 consisti\u00f3 el proceso revolucionario que recorri\u00f3 Europa del Este hacia finales de la d\u00e9cada de 1980 y que nosotros interpretamos como un fen\u00f3meno esencialmente progresivo, a diferencia de gran parte de la izquierda, en particular los actuales partidos comunistas.<\/p>\n<p>Por fin, plantearemos algunas conclusiones para ayudar al debate. Por ejemplo, cu\u00e1les son los programas de los partidos comunistas actuales, que siempre reivindicaron el accionar de la burocracia. Haremos una caracterizaci\u00f3n sobre lo que es hoy el Estado chino, el cubano, y el actual gobierno de Putin en Rusia.<\/p>\n<p>Por \u00faltimo, debatiremos sobre si la degeneraci\u00f3n fue producto del estalinismo o del marxismo. Esto es fundamental para retomar el debate sobre la supuesta superioridad del capitalismo sobre el socialismo y, sobre todo, responder a la pregunta de si contin\u00faa o no siendo viable luchar por el socialismo.<\/p>\n<p>Reiteramos, entonces, nuestra invitaci\u00f3n a hacer este recorrido por la historia de la ex URSS y los ex Estados obreros.<\/p>\n<p><iframe loading=\"lazy\" title=\"A 30 a\u00f1os de su disoluci\u00f3n: \u00bfQu\u00e9 pas\u00f3 en la URSS?\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/hJXGk5SZiAY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Actualmente existen muchos debates entre el activismo que lucha en escala internacional, especialmente sobre c\u00f3mo enfrentar las crisis que impone el capitalismo. Llevamos casi dos a\u00f1os de una pandemia que est\u00e1 muy lejos de ser controlada y que demostr\u00f3, una vez m\u00e1s, que quienes m\u00e1s sufren sus consecuencias son los pa\u00edses pobres y la clase [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":67916,"menu_order":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"litci_post_political_author":"","footnotes":""},"categories":[17082],"tags":[3389,9572,17098,17097,3747],"class_list":["post-67894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-especial-urss","tag-capitalismo","tag-comunismo","tag-ex-estados-obreros","tag-ex-urss","tag-socialismo"],"fimg_url":"https:\/\/litci.org\/es\/wp-content\/uploads\/2021\/12\/Muro.jpg","categories_names":["Especial URSS"],"author_info":{"name":"Administraci\u00f3n Site","pic":"https:\/\/secure.gravatar.com\/avatar\/1fc4a65db396208ca881747f59a66a20c6b8670747457224753e1e98c43f719b?s=96&d=mm&r=g"},"political_author":null,"tagline":"","_links":{"self":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/67894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/comments?post=67894"}],"version-history":[{"count":7,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/67894\/revisions"}],"predecessor-version":[{"id":68036,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/67894\/revisions\/68036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media\/67916"}],"wp:attachment":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media?parent=67894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/categories?post=67894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/tags?post=67894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}