{"id":64178,"date":"2020-12-12T14:47:48","date_gmt":"2020-12-12T14:47:48","guid":{"rendered":"https:\/\/litci.org\/es\/?p=64178"},"modified":"2024-11-03T13:28:43","modified_gmt":"2024-11-03T13:28:43","slug":"la-verdadera-cara-de-la-nueva-normalidad","status":"publish","type":"post","link":"https:\/\/litci.org\/es\/la-verdadera-cara-de-la-nueva-normalidad\/","title":{"rendered":"La verdadera cara de la \u201cnueva normalidad\u201d"},"content":{"rendered":"<p><em>La pandemia de covid-19 ha salido de la primera plana de los diarios. Sin embargo, las cifras de contagios y muertes son alarmantes, peores que en su inicio o en los primeros meses de su desarrollo. La hip\u00f3crita \u201cnueva normalidad\u201d impuesta por las burgues\u00edas de todos los pa\u00edses se cobra su precio que, como siempre, es pagado por los trabajadores.<\/em><!--more--><\/p>\n<p>Por: Alejandro Iturbe<\/p>\n<p>Seg\u00fan los datos proporcionados por la p\u00e1gina oficial de la OMS (Organizaci\u00f3n Mundial de la Salud) al d\u00eda 9 de diciembre se registraba un acumulado de cerca de 68 millones de personas contagiadas y 1.551.214 muertos. El ritmo de nuevos contagios diarios se ubicaba en un promedio de 600.000 y el de muertes en 11.000 (esta \u00faltima cantidad solo es superada por un pico producido en abril pasado)[1].<\/p>\n<p>Es bueno recordar que muchos especialistas han se\u00f1alado que estos n\u00fameros oficiales no muestran plenamente la realidad, sea por ocultamiento intencional por parte de los gobiernos o por d\u00e9ficits en los sistemas de registro.\u00a0 La verdadera cifra ser\u00eda como m\u00ednimo el doble.<\/p>\n<p>Si analizamos los pa\u00edses m\u00e1s afectados, el 2 de diciembre Estados Unidos registr\u00f3 m\u00e1s de 150.000 nuevos casos diarios y 3.157 fallecidos (muy superior al anterior r\u00e9cord de 2.603 muertes de abril) y ya acumula 270.000 muertos[2]. La pandemia ya ha provocado m\u00e1s v\u00edctimas que el n\u00famero de soldados estadounidenses muertos en la Segunda Guerra Mundial.<\/p>\n<p>Los pa\u00edses de Europa, que pensaban que hab\u00edan frenado la din\u00e1mica de contagios, viven una segunda oleada que ya sobrepasa en intensidad la primera. En Latinoam\u00e9rica, se teme que esa segunda oleada llegue sin haber superado o frenado la anterior[3].<\/p>\n<p>El siguiente cuadro, publicado por el diario digital Nexo Jornal el 4 de diciembre pasado, seg\u00fan datos del ECDC (siglas en ingl\u00e9s del Centro Europeo para el Control de Enfermedades) ayuda a ver la situaci\u00f3n actual y su gravedad.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-64180 aligncenter\" src=\"https:\/\/litci.org\/es\/wp-content\/uploads\/2020\/12\/covid.png\" alt=\"\" width=\"551\" height=\"301\" srcset=\"https:\/\/litci.org\/es\/wp-content\/uploads\/2020\/12\/covid.png 551w, https:\/\/litci.org\/es\/wp-content\/uploads\/2020\/12\/covid-300x164.png 300w\" sizes=\"auto, (max-width: 551px) 100vw, 551px\" \/><\/p>\n<p><strong>Una tragedia anunciada<\/strong><\/p>\n<p>\u00bfC\u00f3mo es posible que, casi un a\u00f1o despu\u00e9s de iniciada la pandemia, la situaci\u00f3n sea m\u00e1s grave que el pico producido por su aparici\u00f3n? Hemos respondido a esta pregunta en numerosos art\u00edculos publicados en esta p\u00e1gina en el \u00faltimo a\u00f1o[4].<\/p>\n<p>En esos art\u00edculos expresamos que el brote inicial de Covid-19 en China pod\u00eda considerarse como un \u201checho natural\u201d, como una nueva zoonosis (enfermedades que pasan de los animales a los seres humanos) de las que ya ha padecido la humanidad. Esta consideraci\u00f3n debe ser relativizada por la forma en que el capitalismo est\u00e1 destruyendo la naturaleza, lo que provoca desastres cada vez mayores. Adem\u00e1s, la velocidad de su expansi\u00f3n y la imposibilidad de los gobiernos burgueses de derrotar la pandemia s\u00ed son consecuencia directa del sistema capitalista.<\/p>\n<p>Hubo gobiernos \u201cnegacionistas\u201d que actuaron de modo criminal, como el de Donald Trump en Estados Unidos, y el de Jair Bolsonaro, en el Brasil, que agravaron cualitativamente el cuadro y eso signific\u00f3 que sus pa\u00edses encabezaran la lista mundial de impacto. Pero tambi\u00e9n los gobiernos burgueses que tuvieron una pol\u00edtica m\u00e1s activa de combate al Covid-19 lo hicieron \u201ccon una mano atada\u201d y absolutamente condicionados por su car\u00e1cter de clase y los intereses que defienden. En primer lugar, lo hicieron con sistemas de salud p\u00fablica cada vez m\u00e1s deteriorados y desfinanciados luego de d\u00e9cadas de ataques y de una pol\u00edtica que considera la salud como un campo de negocios de empresas privadas.<\/p>\n<p>En lo esencial, esta realidad no ha cambiado con la pandemia. Por ejemplo, salvo el caso cubano y alguna otra excepci\u00f3n, nunca hubo una verdadera pol\u00edtica de testeos masivos y un aislamiento organizado y basado en esos resultados. De esa forma, incluso en aquellos pa\u00edses que adoptaron medidas de cuarentena, esto se mostr\u00f3 totalmente insuficiente al no ser parte de una pol\u00edtica global seria de combate.<\/p>\n<p>En segundo lugar, a pesar de las medidas de restricci\u00f3n, nunca avanzaron hacia un verdadero aislamiento de emergencia sanitaria, necesario para frenar la expansi\u00f3n. Incluso en los momentos m\u00e1s duros de las restricciones, millones de trabajadores fueron obligados a concurrir a sus trabajos (en ramas esenciales y en otras que no lo eran) y, en ellos, nunca hubo controles serios sobre la protecci\u00f3n que deb\u00edan ofrecer las empresas. Numerosas luchas y huelgas se dieron en el mundo por este motivo, por ejemplo, en Italia, Estados Unidos, Argentina, Brasil y otros pa\u00edses.<\/p>\n<p>En la medida en que estas restricciones parciales potenciaban la crisis econ\u00f3mica que ya ven\u00eda del a\u00f1o anterior[5], los gobiernos comenzaron a sacarse la careta y a mostrar sin tapujos su car\u00e1cter de defensores de las ganancias capitalistas: sin haber derrotado nunca la pandemia, comenzaron una apertura cada vez mayor de las actividades econ\u00f3micas (con el siniestro eslogan de la \u201cnueva normalidad\u201d), multiplicando as\u00ed las posibilidades de contagio.<\/p>\n<p>La realidad muestra que la burgues\u00eda impuls\u00f3 la reapertura completa de la econom\u00eda y de otras actividades y, ahora, cuando le estalla en las manos el resultado de esa pol\u00edtica criminal, no sabe qu\u00e9 hacer y convulsivamente reintroduce algunas medidas restrictivas (como los \u201ctoques de queda\u201d nocturnos o el cierre m\u00e1s temprano de bares) que, aisladas de una pol\u00edtica global de combate serio a la pandemia, acabar\u00e1n siendo est\u00e9riles.<\/p>\n<p>En esta pol\u00edtica de imponer la \u201cnueva normalidad\u201d de explotaci\u00f3n a cualquier costo, no se diferenciaron los gobiernos burgueses negacionistas, como los de Trump y Bolsonaro, con aquellos \u201cpreocupados\u201d y supuestamente \u201cprogresistas\u201d como algunos europeos y el de Alberto Fern\u00e1ndez y Cristina Kirchner en la Argentina. En \u00faltima instancia, estos \u00faltimos solo son m\u00e1s hip\u00f3critas. Esta es la raz\u00f3n de fondo de la persistencia de la pandemia: la avidez de ganancia de la burgues\u00eda, aunque esta sea al costo de la vida de millones de trabajadores.<\/p>\n<p>Lo peor de todo es que acaban ech\u00e1ndole la culpa \u201ca la gente\u201d porque se \u201cexcede\u201d en sus horas libres. Por ejemplo, un especialista del Departamento de Enfermedades Transmisibles de la OMS, frente a la segunda oleada en Europa, declar\u00f3<em>: <\/em><em>\u00abLa lecci\u00f3n es que\u00a0<strong>no debemos bajar la guardia<\/strong>. En Europa, con la llegada del verano y la ca\u00edda de los casos, <strong>se relajaron las medidas<\/strong>\u00ab<\/em>[6]<em>. <\/em><\/p>\n<p>Es decir, para los especialistas de la burgues\u00eda, el problema no es que millones de trabajadores deban ir todos los d\u00edas a trabajar sin reales condiciones de seguridad sanitaria y viajar en transportes p\u00fablicos colmados sino que \u201chan bajado la guardia\u201d\u00a0 y se \u201crelajaron en las medidas\u201d por querer tomar una cerveza en un bar o hacer una escapada al mar.<\/p>\n<p><strong>Los trabajadores son los que m\u00e1s sufren\u00a0 <\/strong><\/p>\n<p>Mientras tanto, la burgues\u00eda ha acu\u00f1ado una expresi\u00f3n siniestra (la \u201cnueva normalidad\u201d) que gobiernos, medios de prensa y las publicidades repiten, para ocultar el desastre del que es responsable.<\/p>\n<p>Se llega a l\u00edmites absurdos como el del gobierno irland\u00e9s que, frente a la pr\u00f3xima navidad, se dirigi\u00f3 a los ni\u00f1os del pa\u00eds declarando que considera <em>\u201clos viajes de Santa Claus como viajes esenciales para fines esenciales. Por lo tanto, est\u00e1 exento de la necesidad de autocuarentena durante 14 d\u00edas y podr\u00e1 entrar y salir del espacio a\u00e9reo irland\u00e9s y de los hogares irlandeses sin tener que restringir sus movimientos\u201d<\/em>[7].<\/p>\n<p>La realidad nos muestra que son los trabajadores, sus familias y sus hijos los que m\u00e1s han sufrido el impacto directo de la pandemia. Numerosos estudios han demostrado que el n\u00famero de contagios y muertes es muy superior en la clase trabajadora y en los sectores pobres que viven en condiciones m\u00e1s precarias y ten\u00edan y tienen menos acceso a los sistemas de salud.<\/p>\n<p>Sobre esta base, tal como hemos dicho, millones se ven obligados a trabajar y a transportarse sin reales condiciones de seguridad sanitaria. Los que m\u00e1s han sido golpeados son, por supuesto, los trabajadores de la salud (sean m\u00e9dicos\/as, enfermeros\/ras, personal de limpieza, etc.), muchos de los cuales han pagado con su vida el estar en la \u201cprimera l\u00ednea\u201d de combate a la pandemia.<\/p>\n<p>Pero las f\u00e1bricas y otros lugares de trabajo se han transformado en focos de contagio y de riesgo masivo. A lo largo de este a\u00f1o, hemos ido mostrando m\u00faltiples ejemplos de ello. Como el de una planta procesadora de carne en Alemania, en la que se contagiaron 650 de sus 1.000 trabajadores[8]. O el de una segunda oleada en Costa Rica, frente a la cual su ministro de Salud reconoci\u00f3:\u00a0<em>\u201cEn estos momentos estamos en la segunda ola pand\u00e9mica (\u2026) Tiene caracter\u00edsticas diferentes a la primera. Estamos teniendo una focalizaci\u00f3n importante en trabajadores del sector agr\u00edcola, empresas empacadoras, y con riesgo en el sector de la construcci\u00f3n\u201d<\/em><em>[9].<\/em><\/p>\n<p><em><strong>Un ejemplo reciente<\/strong><\/em><\/p>\n<p><em>Un ejemplo m\u00e1s reciente se ha dado en la mina Cerro Vanguardia (propiedad de la Anglo Gold Ashanti) en la provincia de Santa Cruz (Argentina). La actividad minera fue declarada \u201cesencial\u201d por el gobierno nacional kirchnerista, y la gobernadora provincial (hermana del fallecido ex presidente N\u00e9stor Kirchner) autoriz\u00f3 <\/em>protocolos hechos a medida de las empresas multinacionales mineras por <em>\u201cla necesidad de recuperar su nivel de producci\u00f3n\u201d<\/em>: el ingreso a los yacimientos de los mineros provenientes de zonas de circulaci\u00f3n comunitaria sin el aislamiento convenido, la habilitaci\u00f3n de m\u00f3dulos habitacionales donde m\u00e1s de 20 trabajadores comparten las mismas duchas, y el permiso para que puedan convivir dos personas en una misma habitaci\u00f3n. Todo esto para garantizar el saqueo de recursos naturales como el oro y la plata.<\/p>\n<p>Todo esto fue avalado por las conducciones sindicales del sector. Incluso algunos representantes del sindicato mayoritario (AOMA) salieron a recolectar firmas para que no haya un cese de actividades, diciendo que, en ese caso, habr\u00eda despidos y rebajas salariales. Eso, en un momento en que ya se hab\u00edan registrado casos positivos al interior de los yacimientos. Todo esto fue denunciado por la Agrupaci\u00f3n Minera 27 de Julio, opositora a la burocracia sindical, y tambi\u00e9n por el PSTU de Santa Cruz, pero hab\u00eda un gran sentimiento de bronca en los trabajadores.<\/p>\n<p>En ese marco, el 2 de noviembre pasado la empresa realiz\u00f3 el habitual cambio de turno (se hace cada 14 d\u00edas). El propio servicio m\u00e9dico hab\u00eda detectado que 40 trabajadores presentaban s\u00edntomas de contagio pero la empresa los envi\u00f3 a sus puestos de trabajo sin ninguna medida de aislamiento, con alt\u00edsimo riesgo para los dem\u00e1s. La empresa \u201cse lavaba las manos\u201d de las consecuencias.<\/p>\n<p>Esos trabajadores volvieron a sus ciudades en la regi\u00f3n, como Puerto San Juli\u00e1n, y otros puntos del pa\u00eds. Uno de ellos, Rom\u00e1n Ramos, a quien le faltaba muy poco tiempo para jubilarse, fue declarado positivo a los 10 d\u00edas en el hospital de Caleta Olivia tras ser derivado de urgencia desde otro hospital por \u201cfalta de unidad de terapia intensiva\u201d. Pocos d\u00edas despu\u00e9s, falleci\u00f3. Fue un verdadero asesinato, con la empresa como responsable directa, y con c\u00f3mplices: los gobiernos nacional, provincial y municipales, y la burocracia sindical.<\/p>\n<p>Ante ello, los trabajadores de la mina, impulsados por la Agrupaci\u00f3n 27 de Julio, decidieron paralizar las actividades y se lo impusieron a la empresa. Esta se vio obligada a desinfectar todas las instalaciones aunque los protocolos siguen siendo insuficientes., y se han presentados algunos casos nuevos. Pero los mineros siguen en alerta. Una lucha similar se dio en otra empresa de la regi\u00f3n, Minera Santa Cruz, cuyos trabajadores tambi\u00e9n paralizaron la mina con reclamos similares.<\/p>\n<p><strong>Sobre la vacuna y sus plazos<\/strong><\/p>\n<p>En un art\u00edculo publicado hace dos meses, se\u00f1alamos: <em>\u201cEn el marco de una pandemia que persiste, por un lado, y la necesidad de avanzar en la \u2018nueva normalidad\u2019 para recuperar sus niveles explotaci\u00f3n y lucro, por el otro, las burgues\u00edas necesitan desesperadamente una vacuna que pueda ser de aplicaci\u00f3n masiva\u201d<\/em>[10].<\/p>\n<p>Dijimos que sobre las vacunas tambi\u00e9n val\u00eda la figura de la mano atada. Porque, incluso en esta situaci\u00f3n de emergencia, las burgues\u00edas segu\u00edan siendo mezquinas a la hora de invertir en el cuidado de la salud de los trabajadores y el pueblo, gastando \u201cmonedas\u201d en su desarrollo si se lo compara con los paquetes de ayuda que proporcionan a los bancos y las grandes empresas.<\/p>\n<p>Es necesario decir que una vacuna contra el Covid-19, desarrollada con todo rigor cient\u00edfico, ya podr\u00eda existir, porque hubo un brote de coronavirus del SARS en 2002. Pero no fue hecha porque en ese momento afect\u00f3 solo a una parte de la poblaci\u00f3n de Asia y eso no daba ganancias suficientes para los grandes laboratorios.<\/p>\n<p>Al mismo tiempo, la \u201ccarrera\u201d de laboratorios y gobiernos por la vacuna no se hizo de modo combinado y cooperativo, \u00fanica forma de hallar r\u00e1pidamente una vacuna efectiva, sino a trav\u00e9s de una feroz competencia de empresas (y de gobiernos) por llegar primeros en la \u201ccarrera\u201d para lucrar con ese \u201ctriunfo\u201d.<\/p>\n<p>En estas condiciones, las vacunas ser\u00e1n lanzadas para su aplicaci\u00f3n masiva sin que se haya verificado con verdadera seriedad su efectividad (porcentaje de inmunizaci\u00f3n de quienes la toman) ni los efectos colaterales negativos que puedan producir. Por ejemplo, AstraZeneca anunci\u00f3 que la vacuna que desarroll\u00f3 en conjunto con la Universidad de Oxford era entre el 62 y el 90% efectiva (\u00bf?)[11]. En realidad, ser\u00edan necesarios unos meses y m\u00e1s testes para valorar la efectividad de cada vacuna. Ante eso, muchas personas tienen dudas en vacunarse.<\/p>\n<p><strong>Vacunas para todos<\/strong><\/p>\n<p>La burgues\u00eda y sus gobiernos necesitan disponer de una vacuna para avanzar en la \u201cnueva normalidad\u201d de explotaci\u00f3n y recuperaci\u00f3n de ganancias. Su inter\u00e9s no es \u201chumanitario\u201d sino mezquino. Pero lo cierto es que la gran mayor\u00eda de los trabajadores tambi\u00e9n esperan con ansiedad la vacuna para no correr riesgos en su obligaci\u00f3n diaria de trabajar y tambi\u00e9n para poder retomar sin restricciones las pocas actividades de esparcimiento que tienen en sus duras vidas de explotaci\u00f3n cotidiana.<\/p>\n<p>Hemos dicho que las vacunas ser\u00e1n lanzadas sin haber sido probadas plenamente. Sin embargo, en este contexto de persistencia de la pandemia, para los trabajadores, incluso una vacunaci\u00f3n de efectividad parcial es mejor que ninguna. Creemos, entonces, que las vacunas contra el Covid-19 debe ser de aplicaci\u00f3n obligatoria y absolutamente gratuitas, con su costo a cargo de los gobiernos y las empresas; que debe haber un seguimiento sanitario tambi\u00e9n gratuito de quienes la han recibido y, finalmente, que deben ser los gobiernos y las empresas productoras los que se hagan cargo de la atenci\u00f3n de los efectos secundarios que puedan tener.<\/p>\n<p>Esto nos plantea un nuevo reclamo de lucha. Seg\u00fan la OMS ser\u00eda necesario vacunar a 70% de la poblaci\u00f3n mundial para lograr lo que se llama \u201cinmunidad de reba\u00f1o\u201d[12]. Eso exigir\u00eda un operativo de vacunaci\u00f3n in\u00e9dito en la historia de la humanidad, con las inversiones que sean necesarias para llevarlo a cabo y una cooperaci\u00f3n internacional absolutamente in\u00e9dita y opuesta a la feroz competencia actual.<\/p>\n<p>Frente a esta necesidad perentoria, algunos gobiernos, como el de Jair Bolsonaro en el Brasil, tienen la actitud criminal de no apoyar la vacunaci\u00f3n. El de Donald Trump ya hab\u00eda comprado una cantidad suficiente (300 millones de dosis) pero el resto del mundo (del que su pa\u00eds extrae gran parte de su fabulosa riqueza) \u201cque se arregle\u201d.<\/p>\n<p>Mientras tanto, otros gobiernos favorables a la vacuna muestran nuevamente su mezquindad con planes para una vacunaci\u00f3n nacional en 2021 muy inferior a la requerida. En Espa\u00f1a y Argentina, por ejemplo, con poblaciones superiores a los 40 millones de habitantes, los gobiernos planifican una campa\u00f1a de 10 y 12 millones respectivamente. Adem\u00e1s, esta vacunaci\u00f3n insuficiente se realizar\u00e1 a lo largo de varios meses, con determinados criterios de prioridades.<\/p>\n<p>La \u201cnueva normalidad\u201d implica no solo la aceptaci\u00f3n de los despidos, el deterioro del salario, la p\u00e9rdida de conquistas, el aumento de la pobreza y la miseria que la burgues\u00eda ocasion\u00f3 con la pandemia, sino tambi\u00e9n que millones de trabajadores seguir\u00e1n teniendo alto riesgo de contagio y, como vimos, de muerte.<\/p>\n<p>La lucha por verdaderas medidas de seguridad sanitaria por parte de gobiernos y empresas y por vacunas para todos est\u00e1 a la orden del d\u00eda. Esto debe ser parte de una lucha por inversiones masivas en la salud p\u00fablica destinada a los trabajadores y el pueblo. Los especialistas m\u00e1s serios han dicho que es posible la aparici\u00f3n futura de nuevas cepas o virus, y recrudecimiento de enfermedades.<\/p>\n<p>Es la propia vida de la clase trabajadora la que est\u00e1 en juego. El ejemplo que hemos dado de los mineros argentinos, y muchos otros trabajadores en el mundo, muestra que esa lucha es necesaria y posible.<\/p>\n<p>Notas:<\/p>\n<p>[1] <a href=\"https:\/\/covid19.who.int\/?gclid=Cj0KCQiA2af-BRDzARIsAIVQUOcpD9kLytMBOCf8ileisrGaHtsi20RWUpmuSbQeBTIW8zaEpdOI2uEaAk4zEALw_wcB\" target=\"_blank\" rel=\"noopener\">https:\/\/covid19.who.int\/?gclid=Cj0KCQiA2af-BRDzARIsAIVQUOcpD9kLytMBOCf8ileisrGaHtsi20RWUpmuSbQeBTIW8zaEpdOI2uEaAk4zEALw_wcB<\/a><\/p>\n<p>[2] <a href=\"https:\/\/www.nexojornal.com.br\/podcast\/2020\/12\/03\/O-novo-recorde-di%C3%A1rio-de-mortes-por-covid-19-nos-EUA?utm_medium=Email&amp;utm_campaign=SDS&amp;utm_source=SDS\" target=\"_blank\" rel=\"noopener\">https:\/\/www.nexojornal.com.br\/podcast\/2020\/12\/03\/O-novo-recorde-di%C3%A1rio-de-mortes-por-covid-19-nos-EUA?utm_medium=Email&amp;utm_campaign=SDS&amp;utm_source=SDS<\/a><\/p>\n<p>[3] <a href=\"https:\/\/www.bbc.com\/mundo\/noticias-55016466\" target=\"_blank\" rel=\"noopener\">https:\/\/www.bbc.com\/mundo\/noticias-55016466<\/a><\/p>\n<p>[4] Ver esos art\u00edculos en: <a href=\"https:\/\/litci.org\/es\/?s=covid\">https:\/\/litci.org\/es\/?s=covid<\/a>\u00a0 y <a href=\"https:\/\/litci.org\/es\/?s=pandemia\">https:\/\/litci.org\/es\/?s=pandemia<\/a><\/p>\n<p>[5] Sobre este tema, recomendamos ver: <a href=\"https:\/\/litci.org\/es\/hacia-donde-va-la-economia-mundial\/\">https:\/\/litci.org\/es\/hacia-donde-va-la-economia-mundial\/<\/a><\/p>\n<p>[6] <a href=\"https:\/\/www.bbc.com\/mundo\/noticias-55016466\" target=\"_blank\" rel=\"noopener\">https:\/\/www.bbc.com\/mundo\/noticias-55016466<\/a><\/p>\n<p>[7] <a href=\"https:\/\/www.pagina12.com.ar\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.pagina12.com.ar\/<\/a> , ver \u201cPirulo de Tapa\u201d en la edici\u00f3n del 8\/12\/2020<\/p>\n<p>[8] <a href=\"https:\/\/www.dw.com\/es\/rebrote-en-alemania-m%C3%A1s-de-650-infectados-de-coronavirus-en-una-f%C3%A1brica-de-carne\/a-53848869\" target=\"_blank\" rel=\"noopener\">https:\/\/www.dw.com\/es\/rebrote-en-alemania-m%C3%A1s-de-650-infectados-de-coronavirus-en-una-f%C3%A1brica-de-carne\/a-53848869<\/a><\/p>\n<p>[9] <a href=\"https:\/\/www.elpais.cr\/2020\/06\/15\/el-rebrote-del-coronavirus-en-varios-paises-pone-en-alerta-al-mundo\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.elpais.cr\/2020\/06\/15\/el-rebrote-del-coronavirus-en-varios-paises-pone-en-alerta-al-mundo\/<\/a><\/p>\n<p>[10] <a href=\"https:\/\/litci.org\/es\/63611-2\/\">https:\/\/litci.org\/es\/63611-2\/<\/a><\/p>\n<p>[11] <a href=\"https:\/\/www.portafolio.co\/economia\/la-efectividad-de-la-vacuna-astrazeneca-en-validacion-546992\" target=\"_blank\" rel=\"noopener\">https:\/\/www.portafolio.co\/economia\/la-efectividad-de-la-vacuna-astrazeneca-en-validacion-546992<\/a><\/p>\n<p>[12] <a href=\"https:\/\/www.expansion.com\/sociedad\/2020\/11\/11\/5fac2a9b468aeb903d8b4578.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.expansion.com\/sociedad\/2020\/11\/11\/5fac2a9b468aeb903d8b4578.html<\/a><\/p>\n<p>[13] <a href=\"https:\/\/www.elmundo.es\/ciencia-y-salud\/salud\/2020\/11\/10\/5faa4d75fdddffa2728b466a.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.elmundo.es\/ciencia-y-salud\/salud\/2020\/11\/10\/5faa4d75fdddffa2728b466a.html<\/a> y <a href=\"https:\/\/www.cronista.com\/economiapolitica\/Coronavirus-el-Gobierno-espera-empezar-con-la-vacunacion-en-la-primera-quincena-de-enero-20201124-0055.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.cronista.com\/economiapolitica\/Coronavirus-el-Gobierno-espera-empezar-con-la-vacunacion-en-la-primera-quincena-de-enero-20201124-0055.html<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pandemia de covid-19 ha salido de la primera plana de los diarios. Sin embargo, las cifras de contagios y muertes son alarmantes, peores que en su inicio o en los primeros meses de su desarrollo. La hip\u00f3crita \u201cnueva normalidad\u201d impuesta por las burgues\u00edas de todos los pa\u00edses se cobra su precio que, como siempre, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":64179,"menu_order":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"litci_post_political_author":"","footnotes":""},"categories":[15122],"tags":[15045,15121],"class_list":["post-64178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronavirus","tag-coronavirus","tag-pandemia"],"fimg_url":"https:\/\/litci.org\/es\/wp-content\/uploads\/2020\/12\/9c84e9f6-e496-11ea-8e8d-92e5de2d33e5_image_hires_165159.jpg","categories_names":["Pandemia"],"author_info":{"name":"Kely","pic":"https:\/\/secure.gravatar.com\/avatar\/19003bf6219614b90207b39bd4a2733ce9cf96693efdfd639b15a829beed53d1?s=96&d=mm&r=g"},"political_author":null,"tagline":"","_links":{"self":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/64178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/comments?post=64178"}],"version-history":[{"count":1,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/64178\/revisions"}],"predecessor-version":[{"id":64181,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/64178\/revisions\/64181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media\/64179"}],"wp:attachment":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media?parent=64178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/categories?post=64178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/tags?post=64178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}