{"id":57561,"date":"2019-11-07T10:58:07","date_gmt":"2019-11-07T13:58:07","guid":{"rendered":"https:\/\/litci.org\/es\/?p=57561"},"modified":"2024-11-03T13:30:32","modified_gmt":"2024-11-03T13:30:32","slug":"el-significado-politico-de-los-ultimos-acontecimientos-en-siria","status":"publish","type":"post","link":"https:\/\/litci.org\/es\/el-significado-politico-de-los-ultimos-acontecimientos-en-siria\/","title":{"rendered":"El significado pol\u00edtico de los \u00faltimos acontecimientos en Siria"},"content":{"rendered":"<p><em>Los \u00faltimos acontecimientos en Siria, o sea, el retiro por Trump de las divisiones americanas del Kurdist\u00e1n sirio (abriendo as\u00ed espacio para que Turqu\u00eda lleve adelante operaciones contra los kurdos en la regi\u00f3n) y el inicio e interrupci\u00f3n de estas operaciones con el acuerdo entre Erdogan y Putin son nuevas expresiones de la crisis pol\u00edtica y de las contradicciones entre las diferentes fuerzas involucradas. Comprender los intereses de cada una de estas es fundamental para comprender lo que est\u00e1 ocurriendo.<\/em><!--more--><\/p>\n<p>Por: POI \u2013 Rusia<\/p>\n<p><strong>El contexto general \u2013 la revoluci\u00f3n<\/strong><\/p>\n<p>El contexto general de lo que pasa es la revoluci\u00f3n que se desarrolla desde 2011 en Siria como parte del proceso general de revoluciones en el mundo \u00e1rabe. En esta, el pueblo sirio, empobrecido bajo la bota de la dictadura de Assad, se levant\u00f3. El odio al gobierno era tan fuerte que la tentativa de Assad de ahogar en sangre la revoluci\u00f3n llev\u00f3 a la divisi\u00f3n de las Fuerzas Armadas de Siria, as\u00ed como en Libia, con una parte pas\u00e1ndose para el lado del pueblo. Fue as\u00ed que la Revoluci\u00f3n Siria se arm\u00f3. La masiva aversi\u00f3n de la poblaci\u00f3n en relaci\u00f3n con Assad llev\u00f3 a este a aplicar la t\u00e1ctica de tierra arrasada, con la eliminaci\u00f3n f\u00edsica de las ciudades sublevadas, junto con sus poblaciones. E incluso as\u00ed la revoluci\u00f3n tom\u00f3 una gran parte del territorio, dej\u00f3 el r\u00e9gimen dictatorial y proimperialista de Assad al borde de la ca\u00edda, pudiendo haber sido derrocado si en socorro del verdugo no hubiese llegado Putin y \u201cnuestro glorioso ej\u00e9rcito\u201d.<\/p>\n<p><strong>La pol\u00edtica del imperialismo: \u201cabsorber\u201d la revoluci\u00f3n<\/strong><\/p>\n<p>Al contrario de todas las leyendas, y a pesar de las contradicciones existentes, el r\u00e9gimen de Assad satisfac\u00eda muy bien al imperialismo. Por un lado, el modelo econ\u00f3mico capitalista, siguiendo las recetas de los institutos financieros mundiales, con la privatizaci\u00f3n progresiva, permit\u00edan al imperialismo llevar adelante e intensificar el saqueo imperialista del pa\u00eds. Por otro lado, la paz garantizada por Assad en la frontera con Israel, aceptando de hecho la ocupaci\u00f3n de las Colinas del Gol\u00e1n y la represi\u00f3n a los campamentos palestinos, garantizaban al imperialismo la seguridad de su puesto militar avanzado en la regi\u00f3n, que es lo que de hecho representa el Estado de Israel.<\/p>\n<p>Es verdad que el r\u00e9gimen de Assad fue incluido por Bush a su tiempo en el \u201cEje del Mal\u201d, junto con Ir\u00e1n, en el marco de la pol\u00edtica del \u201cnuevo siglo americano\u201d. Pero luego de la derrota americana en Irak, el imperialismo americano ya no ten\u00eda fuerzas ni voluntad para derrocar gobiernos, que aunque con algunas contradicciones respetaban su dominio en la regi\u00f3n. Dominio que fue puesto en cuesti\u00f3n por la revoluci\u00f3n \u00e1rabe.<\/p>\n<p>Para poner fin a la Revoluci\u00f3n Siria, as\u00ed como a las revoluciones en T\u00fanez, Libia, Egipto, los imperialismos americano y europeo apostaron, por la raz\u00f3n arriba dicha, en el llamado \u201cproceso pol\u00edtico\u201d, con la transici\u00f3n gradual y pactada de Assad, principal factor de irritaci\u00f3n para el pueblo, realizada entre elecciones y formando un nuevo gobierno, con el cual se podr\u00eda hacer retroceder la lucha del pueblo a los l\u00edmites anteriores y restablecer el control perdido por Assad.<\/p>\n<p>La crisis pol\u00edtica dentro de los Estados Unidos, los impopulares gastos de guerra, y la debilidad pol\u00edtica de Trump limitaron fuertemente sus posibilidades de intervenci\u00f3n militar. Sin embargo, el surgimiento del Estado Isl\u00e1mico, organizaci\u00f3n que a pesar de causar grandes bajas a la revoluci\u00f3n (motivo de satisfacci\u00f3n de todos los opresores), al mismo tiempo era inaceptable para el imperialismo como un factor independiente de desestabilizaci\u00f3n, obligando al imperialismo a una intervenci\u00f3n militar limitada, incluido un apoyo limitado a las tropas kurdas que luchaban contra el Estado Isl\u00e1mico, tambi\u00e9n para mantener el control sobre estas.<\/p>\n<p><strong>El r\u00e9gimen de Putin: ahogar la revoluci\u00f3n en sangre<\/strong><\/p>\n<p>Para Putin la Revoluci\u00f3n Siria, as\u00ed como la ucraniana, significaba un desaf\u00edo especial, pues era capaz de llegar al C\u00e1ucaso ruso musulm\u00e1n, cuyo aplastamiento fue la piedra fundamental del r\u00e9gimen de Putin (en la segunda Guerra de Chechenia). Es el tal\u00f3n de Aquiles de Putin: un ascenso de la lucha en el C\u00e1ucaso significar\u00eda el fin del r\u00e9gimen de Putin y pondr\u00eda en cuesti\u00f3n el modelo por \u00e9l implementado de espoliaci\u00f3n de recursos naturales y atracci\u00f3n de capitales externos. Adem\u00e1s, la salida de Assad, elecciones, y transici\u00f3n de una dictadura a una democracia burguesa, significar\u00eda inevitablemente la p\u00e9rdida de la base militar rusa en una regi\u00f3n estrat\u00e9gica, haz en la manga de Putin en sus negociaciones con el imperialismo. Por eso, a pesar de que Putin, as\u00ed como el imperialismo, defini\u00f3 como tarea principal poner fin a la revoluci\u00f3n, se diferenciaba de este en los m\u00e9todos, apostando no en los mecanismos de la \u201cdemocracia burguesa\u201d (elecciones) sino en la destrucci\u00f3n directa de la revoluci\u00f3n. Solamente la intervenci\u00f3n del ej\u00e9rcito ruso del lado de Assad, conjuntamente con su t\u00e1ctica de tierra arrasada, cerco militar a las ciudades con poblaciones sublevadas, estrangulamiento de ellas por el hambre y su transformaci\u00f3n en ruinas por los bombardeos intensivos, o sea, igual que los nazistas hicieran en Leningrado, pero ahora realizado por nuestro \u201cglorioso ej\u00e9rcito\u201d bajo la direcci\u00f3n de Putin y Shoigu [ministro de las Fuerzas Armadas], llevando a la muerte, seg\u00fan diferentes fuentes, entre 350.000 a medio mill\u00f3n de personas, fue lo que pudo salvar la dictadura de Assad. Este crimen de Putin contra el pueblo sirio ser\u00e1 sin duda recordado por siglos.<\/p>\n<p><strong>Turqu\u00eda: \u201cel problema kurdo\u201d, cuesti\u00f3n central para Erdogan<\/strong><\/p>\n<p>Un componente de la Revoluci\u00f3n Siria fue la intensificaci\u00f3n de la lucha del pueblo kurdo por su autodeterminaci\u00f3n, naci\u00f3n dividida entre Turqu\u00eda, Irak, Siria e Ir\u00e1n, y que nunca posey\u00f3 su propio Estado. Con la Revoluci\u00f3n Siria y la lucha contra el Estado Isl\u00e1mico, el Kurdist\u00e1n sirio se arm\u00f3. La formaci\u00f3n de una estructura estatal en Rojava, en el norte de Siria, y la victoria por mayor\u00eda absoluta en el referendo por la independencia del Kurdist\u00e1n iraqu\u00ed, pusieron a la orden del d\u00eda la posibilidad de realizar esta tarea hist\u00f3rica del pueblo kurdo: la unificaci\u00f3n del Kurdist\u00e1n y su autodeterminaci\u00f3n. Y eso significaba un peligro colosal para Erdogan.<\/p>\n<p>Para Erdogan, el Kurdist\u00e1n tiene m\u00e1s o menos el mismo significado que el C\u00e1ucaso o Ucrania para Putin. De la misma forma como la rebeli\u00f3n de los pueblos y la derrota de Putin en el C\u00e1ucaso amenazaba con la ruina de todo el sistema pol\u00edtico chovinista \u201cgran ruso\u201d del r\u00e9gimen de Putin (de hecho al servicio de la colonizaci\u00f3n del pa\u00eds por los capitales occidentales y de enriquecer a una media docena de oligarcas a costas del pueblo y de los recursos naturales del pa\u00eds), la lucha de los kurdos y una derrota de Erdogan en el Kurdist\u00e1n amenazaba con la ruina de todo el sistema pol\u00edtico chovinista \u201cgran turco\u201d, opresor de todos los trabajadores del pa\u00eds, incluidos los turcos. Por eso, Erdogan \u201cgolpea\u201d a los kurdos con la misma furia con que Putin mataba chechenos. Y de la mism\u00edsima manera como apoy\u00e1ndose en el chovinismo que infecta a los trabajadores rusos en la guerra contra Ucrania y alrededor de \u201cCrimea es nuestra\u201d, Putin consigui\u00f3 poner en la garganta de la poblaci\u00f3n la reforma de la previsi\u00f3n, en la Turqu\u00eda de Erdogan, apoy\u00e1ndose en el chovinismo turco y en la guerra contra los kurdos, este pudo no solamente mantenerse en el gobierno como concentrar m\u00e1s poderes, incluso a pesar de la muy mala situaci\u00f3n social y econ\u00f3mica del pa\u00eds, y que viene empeorando mucho los \u00faltimos a\u00f1os.<\/p>\n<p>Por eso, de la misma forma como la asfixia del C\u00e1ucaso es cuesti\u00f3n de vida o muerte para Putin, ahogar a los kurdos es cuesti\u00f3n de principio para Erdogan. Es eso lo que explica toda su pol\u00edtica en Siria, incluyendo acciones conjuntas de hecho con el Estado Isl\u00e1mico que combat\u00eda contra los kurdos. La provisi\u00f3n de combatientes extranjeros para el Estado Isl\u00e1mico pasaba fundamentalmente por el territorio de Turqu\u00eda, donde tambi\u00e9n el Estado Isl\u00e1mico ten\u00eda la posibilidad de realizar sus operaciones log\u00edsticas. Erdogan obstaculizaba el recibimiento de apoyo a los kurdos para resistir el genocidio perpetrado por el Estado Isl\u00e1mico.<\/p>\n<p>La misma preocupaci\u00f3n con \u201cla cuesti\u00f3n kurda\u201d explica la oposici\u00f3n general de Erdogan a Assad. Erdogan desde el inicio de la revoluci\u00f3n hab\u00eda dejado de ver a Assad como una fuerza pol\u00edtica capaz de poner un freno a los kurdos del Kurdist\u00e1n sirio. En el este punto se concentraba su divergencia con Putin (que llev\u00f3 incluso la ca\u00edda de un avi\u00f3n bombardero ruso hace algunos a\u00f1os), que apoya la dictadura de Assad hasta el fin.<\/p>\n<p><strong>Kurdist\u00e1n: una lucha heroica de un pueblo y una direcci\u00f3n catastr\u00f3fica<\/strong><\/p>\n<p>El pueblo kurdo mostr\u00f3 durante la Revoluci\u00f3n Siria verdadero hero\u00edsmo, en especial en los combates al Estado Isl\u00e1mico, y en el inicio, contra Assad. La crisis de la dictadura de Assad abri\u00f3 espacio para la formaci\u00f3n en el Kurdist\u00e1n sirio de la formaci\u00f3n estatal de Rojava. Junto con la victoria del voto por la independencia en el referendo del Kurdist\u00e1n iraqu\u00ed, eso abri\u00f3 espacio para la realizaci\u00f3n de la tarea hist\u00f3rica del pueblo kurdo: la formaci\u00f3n de un Kurdist\u00e1n unificado e independiente. Sin embargo, su direcci\u00f3n pol\u00edtica condujo esta lucha al callej\u00f3n sin salida dela situaci\u00f3n actual.<\/p>\n<p>La fuerza dominante en el Kurdist\u00e1n turco y sirio (incluyendo el YPG, a las \u00f3rdenes de autodefensa de Siria) es el PKK (Partido de los Trabajadores del Kurdist\u00e1n), de Abdul Occalan, sobre la cual vale la pena decir algunas palabras. Esta es la direcci\u00f3n hist\u00f3rica de los kurdos. El PKK nunca fue un partido revolucionario, de hecho, siempre fue una estructura profundamente burocratizada, que incluso eliminaba f\u00edsicamente a activistas de otras organizaciones de izquierda kurdas.<\/p>\n<p>Al inicio, el PKK levantaba un programa de unificaci\u00f3n e independencia de todo el Kurdist\u00e1n. Pero desde el inicio de los a\u00f1os 2000, luego del encarcelamiento de Occalan en una prisi\u00f3n turca, el programa del PKK se alter\u00f3. La exigencia de unidad e independencia del Kurdist\u00e1n fue sustituida por la exigencia de autonom\u00eda de los territorios habitados por kurdos en los marcos de los Estados actualmente existentes. Es el reflejo del deseo de la burgues\u00eda kurda, interesada antes que todo en el aumento de su parte en los ingresos totales (incluso de la explotaci\u00f3n de petr\u00f3leo), en mantener buenas relaciones y negocios con las burgues\u00edas nacionales de estos Estados y no interesada en la unificaci\u00f3n de los kurdos. En general, el PKK pas\u00f3 a defender abiertamente un proyecto nacional burgu\u00e9s (pero sin la unificaci\u00f3n de la naci\u00f3n), prometiendo la felicidad para los kurdos, incluyendo en su programa hasta el desarrollo ecol\u00f3gicamente sostenible, en los marcos de autonom\u00edas a trav\u00e9s de negociaciones con el imperialismo, con el Estado turco, con Assad, con Putin\u2026 Una utop\u00eda total y una pol\u00edtica que conduc\u00eda a una derrota anunciada. Una parte de este proyecto pas\u00f3 a ser hacer las paces con Assad, o sea, la renuncia al principal objetivo de la Revoluci\u00f3n Siria: la ca\u00edda del dictador (adem\u00e1s de cavar su propia fosa, porque obviamente si Assad se recupera, volver\u00e1 sus armas contra los kurdos, para recuperar el control sobre sus territorios). Lo mismo con la esperanza de ser defendidos por el imperialismo americano (tambi\u00e9n cavando bajo de s\u00ed una fosa). Lo mismo con las limpiezas \u00e9tnicas contra las poblaciones \u00e1rabes en las regiones \u00e9tnicamente mixtas tomadas bajo su control (lo que meti\u00f3 una cu\u00f1a entre los kurdos y los \u00e1rabes que luchaban contra el r\u00e9gimen de Assad, y que hoy se volvi\u00f3 contra los kurdos, pues Erdogan intenta utilizar eso, esforz\u00e1ndose por poblar la zona a lo largo de la frontera turca con refugiados \u00e1rabes que hab\u00edan huido a Turqu\u00eda, incluso debido a las limpiezas \u00e9tnicas promovidas por las YPG, para separar \u00e9tnicamente a los kurdos sirios de los kurdos turcos, obstaculizando la unificaci\u00f3n de su lucha).<\/p>\n<p><strong>La situaci\u00f3n con la operaci\u00f3n turca<\/strong><\/p>\n<p>En la situaci\u00f3n alrededor de la operaci\u00f3n turca se expresan todos los distintos intereses involucrados.<\/p>\n<p>Trump anunci\u00f3 el retiro de las divisiones americanas del Kurdist\u00e1n sirio. En primer lugar, eso refleja el \u201cfactor Trump\u201d y su voluntad de demostrar \u201cpasos reales\u201d, \u201cruptura con el pasado\u201d, disminuci\u00f3n de los gastos en guerras y \u201cel giro para los problemas internos de los Estados Unidos\u201d, para luchar contra su ca\u00edda de popularidad antes de las pr\u00f3ximas elecciones. Los kurdos armados fueron \u00fatiles para la lucha contra el Estado Isl\u00e1mico, pero ahora ellos ya no son necesarios e incluso son inc\u00f3modos, en especial en el contexto de la sociedad hist\u00f3rica entre los Estados Unidos y Turqu\u00eda en los marcos de la OTAN.<\/p>\n<p>Erdogan, para quien la cuesti\u00f3n kurda es la fundamental de la Revoluci\u00f3n Siria, inici\u00f3 una cruzada contra los kurdos sirios, con el objetivo de imponerles una derrota abrumadora, expulsarlos de las fronteras, romper las ligazones de ellos con los kurdos turcos, poblar la regi\u00f3n entre ellos con refugiados \u00e1rabes y de esta forma garantizar su propio poder y su modelo de opresi\u00f3n de los trabajadores turcos. Su promesa de \u201caplastar la cabeza de los terroristas\u201d en relaci\u00f3n con los kurdos es su versi\u00f3n de la l\u00ednea pol\u00edtica de Putin de \u201caplastar en las letrinas\u201d a los pueblos del C\u00e1ucaso, y deja bien claro sus objetivos. Erdogan ve una posibilidad hist\u00f3rica de debilitar la lucha de los kurdos, que traer\u00eda el consecuente fortalecimiento de su poder.<\/p>\n<p>Los imperialismos europeo y americano condenaron la acci\u00f3n turca. Obviamente, no por preocupaciones con el futuro de los kurdos. Su preocupaci\u00f3n es la perspectiva de la masacre. Esta puede, en primer lugar, desestabilizar a\u00fan m\u00e1s la situaci\u00f3n en la regi\u00f3n. En segundo lugar, no ponerse contra esa operaci\u00f3n colocar\u00eda a los gobiernos europeos bajo el fuego de la cr\u00edtica pol\u00edtica interna en cada pa\u00eds (a\u00fan m\u00e1s si consideramos que en Europa viven muchos kurdos), as\u00ed como ocurri\u00f3 cuando el genocidio de Putin-Assad sobre Alepo, donde la inacci\u00f3n del imperialismo min\u00f3 seriamente a los gobiernos de entonces, en especial el de Obama (el episodio de la l\u00ednea roja). En el caso de Trump, un genocidio kurdo an\u00e1logo ser\u00eda directamente acreditado a su pol\u00edtica.<\/p>\n<p>Los gobiernos americano y europeos no est\u00e1n dispuestos a soportar tales costos pol\u00edticos solamente porque Erdogan quiere resolver sus propios problemas. Por eso, el imperialismo por unanimidad se declar\u00f3 contra la operaci\u00f3n turca. Lo que mejor demuestra todo esto fue la carta de Trump a Erdogan, que inclu\u00eda el consejo \u201cno sea idiota\u201d (en el sentido de que \u201cnosotros todos, es claro, comprendemos su lado, pero de todas formas comp\u00f3rtese directo, contr\u00f3lese, usted no est\u00e1 aqu\u00ed solo\u201d).<\/p>\n<p>El r\u00e9gimen de Assad intervino contra la operaci\u00f3n turca porque ya estableci\u00f3 la paz con la direcci\u00f3n kurda y no est\u00e1 interesado en que tiren contra ellos por el momento. Al mismo tiempo, existe la preocupaci\u00f3n de c\u00f3mo queda la cuesti\u00f3n de Idlib, donde sigue la resistencia contra su r\u00e9gimen, con la participaci\u00f3n de organizaciones pro turcas.<\/p>\n<p>Putin, de la misma forma, se posicion\u00f3 contra la operaci\u00f3n, ya que ella trae el riesgo de desestabilizaci\u00f3n y porque los kurdos no est\u00e1n luchando contra Assad. A pesar de toda la amistad con Erdogan, Putin est\u00e1 preocupado con salvar el r\u00e9gimen de Assad y no con la \u201ccuesti\u00f3n kurda\u201d.<\/p>\n<p>Exactamente visando la satisfacci\u00f3n de todos estos distintos y contradictorios (a pesar de no absolutos) elementos, es que Putin y Erdogan dedicaron seis horas de negociaciones a puertas cerradas, que terminaron con un acuerdo aceptable para todas las fuerzas opresoras.<\/p>\n<p>Como resultado del acuerdo, la operaci\u00f3n turca fue interrumpida, que era lo que quer\u00edan el imperialismo y Putin.<\/p>\n<p>Erdogan gan\u00f3 con aceptar una \u201czona de seguridad\u201d (a pesar de menor que la quer\u00eda) y con el retiro parcial de las tropas kurdas (a pesar de que la concreci\u00f3n de eso sea todav\u00eda una cuesti\u00f3n aparte que preocupa a Erdogan). \u00c9l, por lo que todo indica, no tendr\u00e1 la posibilidad de crear una zona tap\u00f3n \u00e9tnica. Pero puede vender el acuerdo conquistado para su p\u00fablico interno como una conquista externa de la \u201cgran Turqu\u00eda que se yergue\u201d y con eso conseguir apoyo para su gobierno, para dar continuidad a sus ataques contra los trabajadores turcos.<\/p>\n<p>Assad gan\u00f3 con la participaci\u00f3n de Rusia en el patrullaje de la zona de seguridad conjuntamente con el ej\u00e9rcito turco, como garant\u00eda de que los turcos no estar\u00e1n all\u00ed solos y no podr\u00e1n hacer lo que quieran, as\u00ed como gan\u00f3 la posibilidad de patrullar por cuenta propia algunos territorios y de pasada tener bajo su control algunas ciudades que hasta entonces estaban ocupadas por los kurdos.<\/p>\n<p>Putin evit\u00f3 una masacre que no le era necesaria, se fortaleci\u00f3 en la regi\u00f3n en el papel de participante de peso en la situaci\u00f3n, y demostr\u00f3 al imperialismo su utilidad y su capacidad de alcanzar aquello que el imperialismo por s\u00ed solo no puede por el momento.<\/p>\n<p>La gran v\u00edctima son los kurdos, cuyo justo derecho a la autodeterminaci\u00f3n y la unidad nacional sigue siendo pisoteado.<\/p>\n<p>El acuerdo firmado entre Putin y Erdogan se orienta a satisfacer los distintos intereses contradictorios de las fuerzas opresoras. El acuerdo significa el env\u00edo de tropas rusas a Siria para controlar las zonas disputadas, con todos los costos que eso implica. Obviamente, el r\u00e9gimen de Putin intenta vender a los rusos que esta fue una \u201cconquista para Rusia\u201d, que justificar\u00eda toda la pol\u00edtica contra los trabajadores llevada a cabo. Los trabajadores rusos no deben caer en esta mentira.<\/p>\n<p>Traducci\u00f3n: Natalia Estrada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los \u00faltimos acontecimientos en Siria, o sea, el retiro por Trump de las divisiones americanas del Kurdist\u00e1n sirio (abriendo as\u00ed espacio para que Turqu\u00eda lleve adelante operaciones contra los kurdos en la regi\u00f3n) y el inicio e interrupci\u00f3n de estas operaciones con el acuerdo entre Erdogan y Putin son nuevas expresiones de la crisis pol\u00edtica [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":57562,"menu_order":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"litci_post_political_author":"","footnotes":""},"categories":[2695,6883,2645,2667,2704,2715,2716],"tags":[14847,3209,3035,5319,3066,3756,4255,3696,2873],"class_list":["post-57561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados-unidos","category-kurdistan","category-mundo","category-poi-rusia","category-rusia","category-siria","category-turquia","tag-assad-y-putin","tag-erdogan","tag-imperialismo-2","tag-kurdistan","tag-kurdos","tag-putin","tag-revolucion-siria","tag-rusia-2","tag-turquia-2"],"fimg_url":"https:\/\/litci.org\/es\/wp-content\/uploads\/2019\/11\/putin-erdogan.jpg","categories_names":["Estados Unidos","Kurdist\u00e1n","Mundo","POI - Rusia","Rusia","Siria","Turqu\u00eda"],"author_info":{"name":"Administraci\u00f3n Site","pic":"https:\/\/secure.gravatar.com\/avatar\/1fc4a65db396208ca881747f59a66a20c6b8670747457224753e1e98c43f719b?s=96&d=mm&r=g"},"political_author":null,"tagline":"","_links":{"self":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/57561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/comments?post=57561"}],"version-history":[{"count":2,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/57561\/revisions"}],"predecessor-version":[{"id":57578,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/57561\/revisions\/57578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media\/57562"}],"wp:attachment":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media?parent=57561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/categories?post=57561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/tags?post=57561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}