{"id":43967,"date":"2017-05-23T10:03:54","date_gmt":"2017-05-23T12:03:54","guid":{"rendered":"http:\/\/litci.org\/es\/?p=43967"},"modified":"2017-05-23T10:08:46","modified_gmt":"2017-05-23T12:08:46","slug":"tsipras-aprueba-las-nuevas-exigencias-criminales-de-la-troika","status":"publish","type":"post","link":"https:\/\/litci.org\/es\/tsipras-aprueba-las-nuevas-exigencias-criminales-de-la-troika\/","title":{"rendered":"Tsipras aprueba las nuevas exigencias criminales de la Troika"},"content":{"rendered":"<p><em>El 18 de mayo, un d\u00eda <strong>despu\u00e9s de la huelga general<\/strong>, rodeados de miles de manifestantes y con paros todav\u00eda en el transporte p\u00fablico, ferris y hospitales, los diputados de Syriza y de su socio de gobierno (\u201cGriegos independientes\u201d) han hecho votar al Parlamento griego el nuevo y brutal paquete de medidas exigido por la troika (Comisi\u00f3n Europea, Banco Central Europeo, FMI). De esta manera, el gobierno Tsipras podr\u00e1 recibir 7000 millones de euros del segundo tramo del tercer \u201crescate\u201d griego, con los cuales reembolsar la deuda que vence el mes de julio. Por supuesto, los fondos no van a ser para ning\u00fan gasto social o productivo; por el contrario, s\u00f3lo servir\u00e1n para seguir pagando a la troika una deuda incobrable y alimentando la rueda criminal del <strong>saqueo de Grecia<\/strong>, reducida a un estatus de <strong>semicolonia alemana<\/strong>.<\/em><!--more--><\/p>\n<p>Por: Felipe Alegr\u00eda<\/p>\n<p><strong>Las medidas aprobadas<\/strong><\/p>\n<p>El paquete votado por Syriza tiene m\u00e1s de 100 medidas, buena parte de las cuales estaba incluida en la lista de exigencias que la troika manten\u00eda desde 2010, sin que ning\u00fan gobierno se hubiera atrevido a aprobarlas hasta ahora. En realidad, como han denunciado los sindicatos griegos, lo que ha firmado Tsipras no es otra cosa que un <strong>cuarto memorando<\/strong>, sin que esta vez puedan siquiera alegar la excusa de un nuevo \u201crescate\u201d. El texto aprobado, \u201cSuplemento al Memor\u00e1ndum\u201d, lo deja bien claro: \u201cel \u00e9xito del programa requiere la <strong>aplicaci\u00f3n continuada en el tiempo de las pol\u00edticas acordadas para muchos a\u00f1os<\/strong>\u201d. Es la naturalizaci\u00f3n de la sumisi\u00f3n y del expolio.<\/p>\n<p>El paquete incluye un nuevo hachazo a las<strong> pensiones p\u00fablicas<\/strong> (\u00a1y ya van 14!) que entrar\u00e1 en vigor en 2019. La reforma reducir\u00e1 la cuant\u00eda global de las pensiones griegas en un 1% del PIB y eliminar\u00e1 definitivamente el EKAS, un fondo de ayuda de supervivencia a los 380.000 jubilados con menores ingresos. El diario \u201cP\u00fablico\u201d narra el caso de Melina Kotsaki, azafata retirada de 73 a\u00f1os que cuando se jubil\u00f3 cobraba una pensi\u00f3n de 2.200 euros y ahora, tras los sucesivos recortes, cobra 750, que con el nuevo tijeretazo se reducir\u00e1n en un 18%. Menciona tambi\u00e9n el caso de Kostas Kekas, camillero reci\u00e9n jubilado con una pensi\u00f3n de 700 euros, que se ver\u00e1 afectado, como todos los pensionistas, en proporciones parecidas.<\/p>\n<p>Una <strong>nueva reforma fiscal <\/strong>subir\u00e1 los impuestos por valor del 1% del PIB a partir de 2020. Rebajar\u00e1 el m\u00ednimo exento de tributaci\u00f3n, afectando de lleno a los sectores con menores ingresos, y aumentar\u00e1 tambi\u00e9n las contribuciones a los profesionales.<\/p>\n<p>El paquete incluye <strong>nuevos recorte a las prestaciones sociales<\/strong>. \u201cAhorra\u201d 259 millones a costa del subsidio a los parados y de la ayuda a las familias m\u00e1s pobres para pagar la calefacci\u00f3n o atender a los discapacitados. Otros 313 millones desaparecer\u00e1n en dos a\u00f1os del <strong>sistema sanitario<\/strong>, ya grav\u00edsimamente golpeado, al haber perdido un tercio del presupuesto de 2009.<\/p>\n<p>Los <strong>derechos laborales<\/strong> van a verse igualmente afectados al eliminarse trabas legales al despido colectivo. Los convenios seguir\u00e1n sin ser reconocidos. Las convocatorias de huelga ser\u00e1n m\u00e1s dif\u00edciles pues quedar\u00e1n condicionadas al voto favorable del 50% de trabajadores en un contexto marcado por el amedrentamiento patronal y las amenazas de despido. Tambi\u00e9n se relaja la protecci\u00f3n legal a los representantes sindicales.<\/p>\n<p>El expolio del pa\u00eds a trav\u00e9s del saqueo de los presupuestos, se completa con la <strong>venta forzada a precio de saldo del patrimonio p\u00fablico al capital extranjero<\/strong>, muy particularmente al alem\u00e1n. El gobierno y el Fondo de Privatizaci\u00f3n (HRADF) ya le han entregado varios aeropuertos regionales, autopistas, el metro de Atenas o el puerto de El Pireo. Ahora, con las nuevas medidas, buscan hacer lo mismo con la compa\u00f1\u00eda de aguas de Tesal\u00f3nica y Atenas, la petrolera Hellenic Petroleum o la principal el\u00e9ctrica Public Power Corp PPC. El nuevo memorando incluye tambi\u00e9n otro mecanismo de saqueo: el <strong>traspaso de los cr\u00e9ditos morosos de los bancos griegos (100.000 millones) a \u201cfondos buitre\u201d extranjeros<\/strong>, lo que les permitir\u00e1 hacerse con la propiedad de gran n\u00famero de viviendas y negocios a precios irrisorios.<\/p>\n<p><strong>La Uni\u00f3n Europea (UE) al descubierto<\/strong><\/p>\n<p>El nuevo memorando, otra p\u00e1gina negra en la historia de la infamia, nos muestra la verdadera cara de la UE, la de una\u00a0<strong>m\u00e1quina de guerra contra la clase trabajadora y los pueblos de Europa<\/strong>, un instrumento de los grandes bancos y multinacionales europeos para imponer un retroceso generalizado a los trabajadores y someter y saquear a pa\u00edses como Grecia.<\/p>\n<p>La UE es el escudo en el que se apoyan los gobiernos europeos para su ofensiva antiobrera y antipopular y para su pol\u00edtica exterior imperialista. Es un <strong>entramado antidemocr\u00e1tico, dominado por el capital financiero y el gobierno alem\u00e1n<\/strong>, imposible de transformar ni de poner al servicio de los pueblos.<\/p>\n<p><strong>Las mentiras de Tsipras, el ejecutor de la Troika<\/strong><\/p>\n<p>Tsipras ha defendido el nuevo memorando diciendo que as\u00ed despeja el camino para un \u201calivio\u201d de la deuda griega. Ha a\u00f1adido tambi\u00e9n que compensar\u00e1 los recortes con \u201ccontramedidas\u201d sociales. Pero, de nuevo, <strong>miente descaradamente,<\/strong>como lo hizo cuando convoc\u00f3 el refer\u00e9ndum de julio de 2015 convencido de que lo iba a perder y as\u00ed podr\u00eda justificar la aceptaci\u00f3n de las imposiciones de la troika (as\u00ed lo confiesa Varoufakis en su reciente libro de memorias, <em>Adults In The Room).<\/em><\/p>\n<p><a href=\"http:\/\/litci.org\/es\/wp-content\/uploads\/2017\/05\/syriza.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-43968\" src=\"http:\/\/litci.org\/es\/wp-content\/uploads\/2017\/05\/syriza-300x160.jpg\" alt=\"\" width=\"300\" height=\"160\" srcset=\"https:\/\/litci.org\/es\/wp-content\/uploads\/2017\/05\/syriza-300x160.jpg 300w, https:\/\/litci.org\/es\/wp-content\/uploads\/2017\/05\/syriza.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Las declaraciones de Tsipras sobre el alivio de la deuda son pura palabrer\u00eda, en primer lugar porque Alemania se opone rotundamente y, en segundo lugar, porque la propuesta del FMI de cancelar una parte de ella no es, en realidad, m\u00e1s que un mecanismo para perpetuarla, sabiendo que Grecia no puede hacer frente a su actual deuda, cercana al 180% del PIB. En cuanto a las \u201ccontramedidas de alivio\u201d (que, por lo dem\u00e1s, no cambiar\u00edan en nada la situaci\u00f3n general), su margen de maniobra es tambi\u00e9n inexistente, pues el Eurogrupo ha condicionado cualquier \u201cmedida expansiva\u201d a que el pa\u00eds supere los objetivos de super\u00e1vit primario (3,5% del PIB) y tenga un crecimiento del 3,5% del PIB en los pr\u00f3ximos a\u00f1os<\/p>\n<p>Tsipras ha demostrado que <strong>si uno se somete a la Uni\u00f3n Europea y al Euro, por muchas promesas y discursos que haga en la oposici\u00f3n<\/strong>,<strong> en cuanto llega al gobierno se convierte en el ejecutor de sus planes<\/strong>.<\/p>\n<p>Durante todo un tiempo, el grueso de la izquierda europea (Podemos, Izquierda Unida, el Bloco de Esquerda, el Front de Gauche o Die Linke) <strong>present\u00f3 a Tsipras y a Syriza como los grandes h\u00e9roes de la izquierda y como modelo a seguir frente a una socialdemocracia <\/strong>entregada al neoliberalismo y en ca\u00edda libre<strong>.<\/strong> Sin embargo, unos meses despu\u00e9s, Syriza lleg\u00f3 al gobierno y se convirti\u00f3 en el sustituto del PASOK y de la derecha griega, en el nuevo sicario de la troika, en el gestor de la pol\u00edtica criminal de la UE contra los refugiados, invitado permanente a la c\u00fapula de la socialdemocracia europea y socio y amigo de Israel. <strong>Todav\u00eda esperamos de los amigos de Tsipras una cr\u00edtica y un repudio<\/strong> a su gobierno y su pol\u00edtica.<\/p>\n<p><strong>La respuesta de la clase trabajadora griega<\/strong><\/p>\n<p>La respuesta al \u00faltimo memorando ha sido la sexta huelga general contra Tsipras y la troika. Pararon los ferrocarriles, el transporte urbano y mar\u00edtimo, los controladores a\u00e9reos, los medios de comunicaci\u00f3n, los hospitales p\u00fablicos, los funcionarios y, en escala menor, los trabajadores del sector privado. Salieron a la calle por miles, junto a los pensionistas, j\u00f3venes, parados, campesinos y sectores de la clase media arruinada.<\/p>\n<p>La verdad es que no se le puede exigir m\u00e1s a un pueblo heroico que ha sufrido una devastaci\u00f3n econ\u00f3mica y social equivalente a la de una guerra; un pueblo que ha sido vilmente traicionado, primero por el PASOK y despu\u00e9s por Syriza. No se le puede pedir m\u00e1s cuando la convocatoria era a una huelga de 24 horas, testimonial y aislada de una perspectiva estrat\u00e9gica de repudio del pago de la deuda, ruptura con la UE y el Euro, nacionalizaci\u00f3n de los bancos y toma de la econom\u00eda en sus manos. No se le puede pedir m\u00e1s a una clase trabajadora que ha quedado aislada internacionalmente, abandonada por la burocracia sindical, la socialdemocracia y los amigos de Tsipras.<\/p>\n<p><strong>Es necesario construir una respuesta internacionalista<\/strong><\/p>\n<p>Es hora de levantar la solidaridad activa con la clase trabajadora y el pueblo griego, de ir construyendo una respuesta internacionalista a escala europea. Una respuesta apoyada en el sindicalismo combativo y en una izquierda que tenga claro que no hay salida sin enfrentarse de forma unificada a la Europa del Capital y sin abrir una v\u00eda de ruptura revolucionaria con la UE y el Euro, sobre cuya base construir la Europa de los Trabajadores y los Pueblos, los Estados Unidos Socialistas de Europa.<\/p>\n<p>Art\u00edculo publicado en www.corrienteroja.net<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 18 de mayo, un d\u00eda despu\u00e9s de la huelga general, rodeados de miles de manifestantes y con paros todav\u00eda en el transporte p\u00fablico, ferris y hospitales, los diputados de Syriza y de su socio de gobierno (\u201cGriegos independientes\u201d) han hecho votar al Parlamento griego el nuevo y brutal paquete de medidas exigido por la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":43985,"menu_order":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"litci_post_political_author":"","footnotes":""},"categories":[2698,2737],"tags":[10586,10584,10587,10585,10058],"class_list":["post-43967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grecia","category-movimiento-obrero","tag-clase-trabajadora-griega-alternativa-de-los-trabajadores","tag-grecia-troika","tag-sindicatos-izquierda-solidaridad-respuesta-internacional-de-clase","tag-syriza-tsipras-planes-de-austeridad","tag-union-europea-euro"],"fimg_url":"https:\/\/litci.org\/es\/wp-content\/uploads\/2017\/05\/Actualidad_99750859_769398_1706x1280.jpg","categories_names":["Grecia","Movimiento Obrero"],"author_info":{"name":"Administraci\u00f3n Site","pic":"https:\/\/secure.gravatar.com\/avatar\/1fc4a65db396208ca881747f59a66a20c6b8670747457224753e1e98c43f719b?s=96&d=mm&r=g"},"political_author":null,"tagline":"","_links":{"self":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/43967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/comments?post=43967"}],"version-history":[{"count":7,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/43967\/revisions"}],"predecessor-version":[{"id":43995,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/43967\/revisions\/43995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media\/43985"}],"wp:attachment":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media?parent=43967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/categories?post=43967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/tags?post=43967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}