{"id":31323,"date":"2015-11-03T08:12:30","date_gmt":"2015-11-03T10:12:30","guid":{"rendered":"http:\/\/litci.org\/es\/?p=31323"},"modified":"2016-08-03T15:22:46","modified_gmt":"2016-08-03T17:22:46","slug":"el-costo-de-ser-parte-de-la-ue-y-la-zona-euro","status":"publish","type":"post","link":"https:\/\/litci.org\/es\/el-costo-de-ser-parte-de-la-ue-y-la-zona-euro\/","title":{"rendered":"El costo de ser parte de la UE y la zona euro"},"content":{"rendered":"<p><em>Se\u00f1alamos en otras ocasiones que a partir de su ingreso en la zona euro, Grecia recorri\u00f3 el camino que lleva de ser socio menor de la cadena imperialista a transformarse en una semicolonia de las potencias imperialistas europeas, especialmente de Alemania. Algunas elaboraciones dentro de la LIT-CI consideran que ese car\u00e1cter semicolonial ya comenz\u00f3 a ser construido a partir de la segunda posguerra y que ahora se ha profundizado al extremo.<\/em><!--more--><\/p>\n<p>Por: Alejandro Iturbe<\/p>\n<p>a definici\u00f3n de semicolonia parte del hecho de que el pa\u00eds ha firmado pactos pol\u00edticos y econ\u00f3micos que lo subordinan al imperialismo, como aquellos que lo integran a la UE\u00a0 (1993) y a la zona euro (2001). Tambi\u00e9n existen pactos militares de subordinaci\u00f3n, como la pertenencia de Grecia a la OTAN (Organizaci\u00f3n del Tratado del Atl\u00e1ntico Norte), la alianza militar imperialista encabezada por el imperialismo estadounidense como una pieza clave de su estrategia militar y pol\u00edtica mundial. La OTAN posee cuatro bases en Grecia (Tesal\u00f3nica, Larissa, Preveza y Souda Bay) de alto valor geogr\u00e1fico para el control del Mediterr\u00e1neo oriental. En esta subordinaci\u00f3n al imperialismo, la situaci\u00f3n de Grecia es similar a la de los pa\u00edses latinoamericanos.<\/p>\n<p>Al adoptar el euro como moneda, Grecia renunci\u00f3 al derecho de emitir su propia moneda, por lo que su pol\u00edtica monetaria y financiera (conforme el Tratado de Maastricht) pas\u00f3 a estar supervisada por el BCE (Banco Central Europeo) y controlada por las potencias imperialistas del continente. Es decir, perdi\u00f3 su soberan\u00eda monetaria y financiera.<\/p>\n<p>Esta situaci\u00f3n de base dio un salto al comenzar los acuerdos para los \u201cplanes de rescate\u201d de la deuda externa griega. Estos acuerdos tuvieron dos consecuencias. Por un lado, la Troika (BCE, UE y FMI) pas\u00f3 a dirigir directamente toda la pol\u00edtica econ\u00f3mica griega, con la capacidad de definir qu\u00e9 hab\u00eda que hacer y qu\u00e9 no se pod\u00eda. Por el otro, se expres\u00f3 en planes de ajuste (cuyo eje era garantizar el pago de la deuda externa) que reduc\u00edan cada vez la econom\u00eda del pa\u00eds y atacaban duramente el nivel de vida de los trabajadores y el pueblo. Algunos puntos del reciente acuerdo, como la \u201cprivatizaci\u00f3n\u201d de la recaudaci\u00f3n impositiva, son ya directamente elementos coloniales.<\/p>\n<p>Al mismo tiempo, ese car\u00e1cter semicolonial lleva a un vaciamiento de todo contenido de voluntad popular de las instituciones de la democracia burguesa. Quien realmente gobierna (la Troika) no es elegido por el voto popular. E incluso cuando sus propuestas son claramente rechazadas por el voto popular (como en la elecci\u00f3n de Syriza, en enero pasado y en el reciente plebiscito del 5 de julio), acaban imponi\u00e9ndose planes dictados por voluntad de la Troika, a trav\u00e9s de gobiernos que pasan a actuar como verdaderos \u201cadministradores coloniales\u201d del pa\u00eds.<\/p>\n<p><strong>Un pa\u00eds que se achica<\/strong><\/p>\n<p>Este car\u00e1cter semicolonial y el saqueo de riquezas que significa se expresan con claridad en una gran reducci\u00f3n de la econom\u00eda del pa\u00eds. Inicialmente, la integraci\u00f3n en la UE y la zona euro (en el marco de una fase expansiva de la econom\u00eda mundial) origin\u00f3 un crecimiento del PIB griego en un promedio anual de 4%, entre 2001 y 2006.<\/p>\n<p>Pero estas cifras escond\u00edan un proceso profundo y muy peligroso de \u201csimplificaci\u00f3n\u201d de la econom\u00eda del pa\u00eds. La gran industria pas\u00f3 a concentrarse en una \u00fanica rama (la construcci\u00f3n naval), mientras otras como la miner\u00eda, pr\u00e1cticamente desaparec\u00edan. El otro sector privilegiado fue el turismo y las actividades asociadas. Fueron precisamente los ingresos generados por el turismo y esas actividades asociadas los que permitieron, en esos a\u00f1os, compensar las crecientes importaciones de productos industriales.<\/p>\n<p>Pero en 2006 la econom\u00eda griega se \u201cpar\u00f3\u201d y, hasta 2010 creci\u00f3 apenas 0,10% de promedio anual. El pago de la deuda externa ya pasaba su factura y, al mismo tiempo, se anticipaba la crisis econ\u00f3mica mundial que estallar\u00eda en 2007.<\/p>\n<p>A partir de 2010 comienza el \u201cderrumbe\u201d completo. Con grandes dificultades para pagar la deuda externa, los gobiernos de la Nueva Democracia y el PASOK aceptaron \u201cplanes de rescate-ajuste\u201d cada vez m\u00e1s duros y destructores. El resultado es que, desde 2011 hasta hoy, esos planes hicieron que la econom\u00eda griega decreciera 28%, una verdadera cat\u00e1strofe econ\u00f3mica y social generada por el capitalismo imperialista europeo.<\/p>\n<p><strong>La deuda externa<\/strong><\/p>\n<p>Algunos trabajadores, al escuchar nuestra propuesta de no pago de la deuda externa, nos responden que quien contrajo una deuda debe pagarla, como hace un trabajador que pidi\u00f3 un cr\u00e9dito para comprar una casa, un autom\u00f3vil o un electrodom\u00e9stico. Y que si se endeud\u00f3 por encima de su capacidad de pago la culpa es suya y no del acreedor.<\/p>\n<p>Pero, hay una gran diferencia: quienes contraen las deudas externas de los Estados no son los trabajadores sino los gobiernos burgueses. Y la mayor parte de esas deudas no responde a resolver necesidades del pa\u00eds o del pueblo sino de los banqueros y los empresarios.<\/p>\n<p>Veamos la evoluci\u00f3n de la deuda externa griega, para analizar su composici\u00f3n. En las \u00faltimas d\u00e9cadas, la deuda externa siempre fue relativamente alta comparada con el PIB del pa\u00eds: en 1990, representaba 72%. La integraci\u00f3n a la zona euro (y la p\u00e9rdida de soberan\u00eda monetaria) llevaron ese porcentaje hasta alrededor de 100% y as\u00ed se mantuvo hasta 2005. En 2006 y hasta 2010 (ya en medio de la crisis econ\u00f3mica) salta a 150%, y a partir de los \u201cplanes de rescate\u201d crece hasta 180% del PIB (m\u00e1s de 310.000 millones de euros o 338.000 millones de d\u00f3lares).<\/p>\n<p>Hay que entender qu\u00e9 son realmente los llamados \u201cplanes de rescate\u201d. En realidad, a quien se \u201crescata\u201d es a los bancos acreedores, ya que el pa\u00eds que lo solicita (porque no puede pagar los compromisos previos) no ve un euro ni un d\u00f3lar. Esos planes hacen un movimiento contable que permite que los bancos \u201climpien\u201d sus balances y lo primero que se hace en ellos es \u201cseparar\u201d la parte de los pagos previamente comprometidos y asegurar los pagos futuros.<\/p>\n<p>Al mismo tiempo, se avanza en los compromisos de privatizaciones de empresas del Estado a \u201cprecio de oferta\u201d. En Grecia, por ejemplo, se har\u00e1 un fondo con el resultado de la venta de las pocas \u201cjoyas de la abuela\u201d que quedan en el pa\u00eds (como el puerto del Pireo), para\u2026 pagar la deuda.<\/p>\n<p>Es decir, el pa\u00eds deudor paga y paga: solo en este plan de rescate se \u201creservaron\u201d 13.000 millones de euros (14.170 millones de d\u00f3lares) para los pagos de este a\u00f1o, y que se deben sumar a los 425 millones de euros que ya se hab\u00edan pagado en abril pasado.<\/p>\n<p>Incluso si consider\u00e1semos que la deuda externa griega de 2001 (a\u00f1o de la integraci\u00f3n del pa\u00eds a la zona euro) era \u201cleg\u00edtima\u201d y no fraudulenta (120.000 millones de euros), ella ya ha sido pagada en exceso. Pero, en lugar de eso, la deuda del pa\u00eds se multiplic\u00f3 dos veces y media con la \u201cmagia usurera\u201d del llamado inter\u00e9s compuesto.<\/p>\n<p><strong>\u00bfLas deudas son de honor?<\/strong><\/p>\n<p>En realidad, son las grandes potencias imperialistas las que con su deuda externa han dicho varias veces en la historia: \u201cque Dios se lo pague\u201d. Despu\u00e9s de la Segunda Guerra Mundial, Gran Breta\u00f1a deb\u00eda miles de millones de libras esterlinas a la Argentina por los suministros de alimentos durante el conflicto, pero no los pag\u00f3: declar\u00f3 un bloqueo de libras esterlinas y oblig\u00f3 a la Argentina a aceptar como pago las ya muy obsoletas instalaciones del ferrocarril, empresas de energ\u00eda y de tel\u00e9fonos de su propiedad en el pa\u00eds.<\/p>\n<p>El imperialismo alem\u00e1n saque\u00f3 a la Grecia ocupada por los nazis durante la Segunda Guerra Mundial con pr\u00e9stamos forzosos cuyo valor superar\u00eda hoy los 150.000 millones de euros. A eso hay que sumarle m\u00e1s de 100.000 millones de euros por el estimado de los da\u00f1os ocasionados al pa\u00eds durante la ocupaci\u00f3n. Pero esta deuda (y otras) le fueron perdonadas a Alemania (por orden de EEUU e Inglaterra). Hoy, el imperialismo alem\u00e1n paga ese \u201cfavor\u201d destruyendo nuevamente a Grecia.<\/p>\n<p>Es decir, para las potencias imperialistas, sus deudas (incluso cuando fueron originadas bajo el control de las bayonetas de los prestamistas) no se pagan, pero las de los pa\u00edses semicoloniales con ellos son una \u201ccuesti\u00f3n de honor\u201d.<\/p>\n<p><strong>Las consecuencias para los trabajadores y el pueblo <\/strong><\/p>\n<p>Para los trabajadores y el pueblo griegos, este car\u00e1cter semicolonial y los sucesivos \u201cplanes de rescate-ajuste\u201d tienen consecuencias terribles.<\/p>\n<p>En primer lugar, con un aumento brutal de la desocupaci\u00f3n. Esto ya comenz\u00f3 en el mejor per\u00edodo de integraci\u00f3n a la UE, donde solo en el sector minero fueron eliminados 132.000 puestos de trabajo hasta 2005. El desempleo en el pa\u00eds era de 2% en 1980, y creci\u00f3 a 10% en 2000. A partir de los planes de ajuste iniciados en 2010, hay un salto impresionante que lo llev\u00f3 a 25,6% en abril de 2015 (53,2% para menores de 25 a\u00f1os). Y la situaci\u00f3n no har\u00e1 m\u00e1s que agravarse, ya que el acuerdo recientemente firmado por el gobierno de Syriza se compromete a reducir 150.000 empleos en el sector p\u00fablico.<\/p>\n<p>El poder adquisitivo del salario m\u00ednimo (640 euros) viene decreciendo desde 2009, con una ca\u00edda superior a 30%, lo que lo lleva a niveles por debajo de 1995. Las jubilaciones han sufrido una reducci\u00f3n real de m\u00e1s de 30% y su valor b\u00e1sico (cobrado por la mayor\u00eda de los pensionados) es de 360 euros. Tambi\u00e9n se aument\u00f3 de 62 a 67 a\u00f1os la edad m\u00ednima para cobrar jubilaci\u00f3n completa.<\/p>\n<p>Y esto tambi\u00e9n va a empeorar con el acuerdo firmado por el gobierno de Syriza, que prev\u00e9 la suspensi\u00f3n de acuerdos salariales, el permiso de realizar pactos salariales por empresa sin intervenci\u00f3n de los sindicatos, la limitaci\u00f3n de plazos de vigencia m\u00e1ximos de los acuerdos salariales, el descenso y el congelamiento de los salarios m\u00ednimos, la creaci\u00f3n de contratos de formaci\u00f3n por debajo del salario m\u00ednimo interprofesional, la pr\u00f3rroga del tiempo de prueba a doce meses, la rebaja del plazo de despido y del pago de indemnizaciones, y la ampliaci\u00f3n del empleo temporal.<\/p>\n<p>Agravando al extremo las penurias, el sistema de salud est\u00e1 en situaci\u00f3n de colapso por la gran reducci\u00f3n del gasto sanitario p\u00fablico. Actualmente, se est\u00e1 llevando a cabo una reforma hospitalaria que prev\u00e9, entre otras cosas, la restricci\u00f3n de contrataci\u00f3n de especialistas y de personal de los servicios de urgencias para reducir\u00a0costos elevados e innecesarios. Adem\u00e1s, se continuar\u00e1n reduciendo los gastos por medicamentos. Recordemos que una reciente medida del gobierno de Syriza confisc\u00f3 los fondos de reserva de caja de las dependencias p\u00fablicas (desde los municipios hasta los hospitales), lo que significa que ahora no tienen dinero ni siquiera para comprar un ap\u00f3sito protector.<\/p>\n<p>El porcentaje de poblaci\u00f3n pobre en el pa\u00eds pas\u00f3 de 20,1% en 2009 a 35,8% en 2012, y se estima que en 2015 llegar\u00e1 a casi 40%. No es casual, entonces, que se hayan triplicado los casos de depresi\u00f3n y que el n\u00famero de suicidios haya crecido 45%. Cuando decimos que la vida de los trabajadores y el pueblo se muere dentro del euro, no estamos exagerando.[1]<\/p>\n<p>Como expresamos en otro art\u00edculo, para romper este circuito infernal de decadencia y miseria que genera el saqueo semicolonial, hay que dejar de pagar la deuda externa y romper con la UE y la zona euro.<\/p>\n<p>[1] http:\/\/www.eldiario.es\/agendapublica\/proyecto-europeo\/estaGrecia_0_284871869.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se\u00f1alamos en otras ocasiones que a partir de su ingreso en la zona euro, Grecia recorri\u00f3 el camino que lleva de ser socio menor de la cadena imperialista a transformarse en una semicolonia de las potencias imperialistas europeas, especialmente de Alemania. Algunas elaboraciones dentro de la LIT-CI consideran que ese car\u00e1cter semicolonial ya comenz\u00f3 a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31359,"menu_order":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"litci_post_political_author":"","footnotes":""},"categories":[2765,2698],"tags":[6200,6202,5854,2937,6201],"class_list":["post-31323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-correo-internacional","category-grecia","tag-euro-y-eurozona","tag-imperialismo-y-semicolonia","tag-planes-de-austeridad","tag-troika","tag-union-europea-y-grecia"],"fimg_url":"https:\/\/litci.org\/es\/wp-content\/uploads\/2015\/10\/mendigo-griego.jpg","categories_names":["Correo Internacional","Grecia"],"author_info":{"name":"Administraci\u00f3n Site","pic":"https:\/\/secure.gravatar.com\/avatar\/1fc4a65db396208ca881747f59a66a20c6b8670747457224753e1e98c43f719b?s=96&d=mm&r=g"},"political_author":null,"tagline":"","_links":{"self":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/31323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/comments?post=31323"}],"version-history":[{"count":21,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/31323\/revisions"}],"predecessor-version":[{"id":37771,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/31323\/revisions\/37771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media\/31359"}],"wp:attachment":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media?parent=31323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/categories?post=31323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/tags?post=31323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}