{"id":30582,"date":"2015-10-19T09:45:16","date_gmt":"2015-10-19T12:45:16","guid":{"rendered":"http:\/\/litci.org\/es\/?p=30582"},"modified":"2016-08-03T15:22:46","modified_gmt":"2016-08-03T17:22:46","slug":"grecia-contra-la-privatizacion-del-puerto-del-pireo","status":"publish","type":"post","link":"https:\/\/litci.org\/es\/grecia-contra-la-privatizacion-del-puerto-del-pireo\/","title":{"rendered":"Grecia: contra la privatizaci\u00f3n del Puerto del Pireo"},"content":{"rendered":"<p><em>El s\u00e1bado 10 de octubre se realiz\u00f3 una marcha en el Municipio de Drapetsona, en contra de la privatizaci\u00f3n del puerto. La convocatoria para la concentraci\u00f3n y la marcha fue hecha por el mismo Municipio donde se encuentra el puerto mas grande del pa\u00eds, por\u00a0\u00abla cancelaci\u00f3n de la licitaci\u00f3n para la venta del paquete de participaci\u00f3n mayoritaria en OPP (Organismos del Puerto Pireo) y la eliminaci\u00f3n de cualquier plan de privatizaci\u00f3n posible\u00bb.<\/em><!--more--><\/p>\n<p>Por: Xara Argyris<\/p>\n<p>Las ventas, que estaban en proceso antes de enero de 2015 y que hab\u00edan quedado en suspenso, se retoman y ya est\u00e1n los compradores listos para toda la zona del cord\u00f3n de la Costanera, junto con los espacios libres, los caminos y hasta la Avenida Libertad, en la zona.<\/p>\n<p>Con un grupo del municipio a la cabeza, la columna de unas 1.000 personas recorri\u00f3 5 km atravesando la ciudad y el puerto hasta el Ministerio de Navegaci\u00f3n y Pol\u00edticas Isle\u00f1as.<\/p>\n<div id=\"attachment_30585\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/litci.org\/es\/wp-content\/uploads\/2015\/10\/grecia-puertos.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-30585\" class=\"size-medium wp-image-30585\" src=\"http:\/\/litci.org\/es\/wp-content\/uploads\/2015\/10\/grecia-puertos-300x225.jpg\" alt=\"\u201cSyriza, el puerto es de los trabajadores y el pueblo\u201d\" width=\"300\" height=\"225\" srcset=\"https:\/\/litci.org\/es\/wp-content\/uploads\/2015\/10\/grecia-puertos-300x225.jpg 300w, https:\/\/litci.org\/es\/wp-content\/uploads\/2015\/10\/grecia-puertos.jpg 442w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-30585\" class=\"wp-caption-text\">\u201cSyriza, el puerto es de los trabajadores y el pueblo\u201d<\/p><\/div>\n<p>La participaci\u00f3n fue sin banderas de partidos pero estuvieron presentes agrupaciones pol\u00edticas, del barrio, ecologistas y una comisi\u00f3n del Sindicato de Trabajadores de la Marina Mercante. No estuvieron presentes los trabajadores del puerto, y los vecinos miraban y comentaban entre ellos desde las veredas: \u201c\u2026 ahora, por m\u00e1s que griten se lo van a llevar\u201d, dec\u00eda una de las se\u00f1oras.<\/p>\n<p>Thanasis Kantas, secretario general suplente de PENEN (Union de trabajadores de la marina mercante) dec\u00eda: \u00abdurante cuatro a\u00f1os estuvimos luchando juntos con Syrisa contra las privatizaciones y los despidos, el que es ahora ministro, Theodoro Dritsas, estaba siempre presente&#8230; yo vot\u00e9 a Syriza, pero eso no quiere decir que ahora no vamos a hacer nada\u00bb.<\/p>\n<div id=\"attachment_30583\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/litci.org\/es\/wp-content\/uploads\/2015\/10\/graciela-en-grecia.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-30583\" class=\"size-medium wp-image-30583\" src=\"http:\/\/litci.org\/es\/wp-content\/uploads\/2015\/10\/graciela-en-grecia-300x159.png\" alt=\"Manifestaci\u00f3n en defensa del puerto de Pireo\" width=\"300\" height=\"159\" srcset=\"https:\/\/litci.org\/es\/wp-content\/uploads\/2015\/10\/graciela-en-grecia-300x159.png 300w, https:\/\/litci.org\/es\/wp-content\/uploads\/2015\/10\/graciela-en-grecia.png 750w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-30583\" class=\"wp-caption-text\">Manifestaci\u00f3n en defensa del puerto de Pireo<\/p><\/div>\n<p>El ministro Theodoros Dritsas, en su intervenci\u00f3n en el Parlamento declar\u00f3: \u201cEl Ministerio de Navegaci\u00f3n tiene la obligaci\u00f3n de cumplir los compromisos firmados en el primer y segundo memor\u00e1ndum, continuar con el proceso de Licitaci\u00f3n para la venta de 51% de las acciones de OPP y a continuaci\u00f3n de OLS (Organismos del Puerto de Sal\u00f3nica), con la presentaci\u00f3n de las ofertas de las empresas para OLP durante el mes de octubre\u201d. El mismo proceso licitatorio incluye el di\u00e1logo social por el uso de las tierras y de las instalaciones, as\u00ed como para la regulaci\u00f3n del funcionamiento del puerto sobre la base de los principios de los acuerdos internacionales\u201d. Los posibles compradores que est\u00e1n preparados para dar el zarpazo tal buitres son las empresas china COSCO, danesa APM, y filipinesa ICTS.<\/p>\n<p>A pesar de estas confirmaciones, poder avanzar con la privatizaci\u00f3n del puerto no ser\u00e1 sin reacciones de los organismos sociales, profesionales y autoridades municipales, quienes son perjudicados directamente por la venta de 51% de las acciones. No se trata solo del puerto, se trata del control de la econom\u00eda del pa\u00eds, adem\u00e1s de las tierras que est\u00e1n en el cord\u00f3n de la costanera, donde el municipio de la regi\u00f3n ten\u00eda el proyecto para construir centros de salud. \u201cUna semana antes de las elecciones hac\u00edan la promesa de que la regi\u00f3n quedar\u00eda por fuera\u201d, dec\u00eda el Intendente al diario <em>La \u00c9poca<\/em>\u00a0(11\/10\/15).<\/p>\n<p>Un frente m\u00e1s que queda abierto y en el que comienzan a darse los enfrentamientos con el nuevo Tsipras, y que depender\u00e1 de la coordinaci\u00f3n imprescindible entre todos los sindicatos de los trabajadores del puerto con las organizaciones barriales, sociales y pol\u00edticas, para dar con la unidad una contundente respuesta en la lucha para defender el Puerto, a los habitantes de todos los municipios que lo rodean, los puestos de los trabajadores de todas las especialidades, y para enfrentar la pol\u00edtica del imperialismo y del gobierno que quieren entregar a buitres multinacionales una de las fuentes de riqueza m\u00e1s importante de Grecia.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><a href=\"http:\/\/litci.org\/es\/wp-content\/uploads\/2015\/10\/puerto-del-pireo.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-30586 alignright\" src=\"http:\/\/litci.org\/es\/wp-content\/uploads\/2015\/10\/puerto-del-pireo-300x197.png\" alt=\"puerto del pireo\" width=\"300\" height=\"197\" srcset=\"https:\/\/litci.org\/es\/wp-content\/uploads\/2015\/10\/puerto-del-pireo-300x197.png 300w, https:\/\/litci.org\/es\/wp-content\/uploads\/2015\/10\/puerto-del-pireo.png 921w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Fuera las manos del Puerto Pireo. Formaci\u00f3n de Comit\u00e9 de coordinaci\u00f3n entre sindicatos y organizaci\u00f3n barriales, sociales y pol\u00edticas.<\/li>\n<li>No a la liquidaci\u00f3n de los puertos Pireo y Sal\u00f3nica.<\/li>\n<li>Nacionalizaci\u00f3n del puerto con control obrero.<\/li>\n<li>Abajo los memor\u00e1ndums. No pago de la deuda externa. Ruptura con el euro y la UE.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00e1bado 10 de octubre se realiz\u00f3 una marcha en el Municipio de Drapetsona, en contra de la privatizaci\u00f3n del puerto. La convocatoria para la concentraci\u00f3n y la marcha fue hecha por el mismo Municipio donde se encuentra el puerto mas grande del pa\u00eds, por\u00a0\u00abla cancelaci\u00f3n de la licitaci\u00f3n para la venta del paquete de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30599,"menu_order":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"litci_post_political_author":"","footnotes":""},"categories":[2698,2737],"tags":[3520,6055,6051,6054,6053],"class_list":["post-30582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grecia","category-movimiento-obrero","tag-grecia-3","tag-imperialismo-y-syriza","tag-privatizacion-de-puerto-pireo","tag-syriza-y-los-memorandos","tag-trabajadores-portuarios"],"fimg_url":"https:\/\/litci.org\/es\/wp-content\/uploads\/2015\/10\/puerto-pireo.jpg","categories_names":["Grecia","Movimiento Obrero"],"author_info":{"name":"Administraci\u00f3n Site","pic":"https:\/\/secure.gravatar.com\/avatar\/1fc4a65db396208ca881747f59a66a20c6b8670747457224753e1e98c43f719b?s=96&d=mm&r=g"},"political_author":null,"tagline":"","_links":{"self":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/30582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/comments?post=30582"}],"version-history":[{"count":36,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/30582\/revisions"}],"predecessor-version":[{"id":37772,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/posts\/30582\/revisions\/37772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media\/30599"}],"wp:attachment":[{"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/media?parent=30582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/categories?post=30582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/litci.org\/es\/wp-json\/wp\/v2\/tags?post=30582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}