{"id":4432,"count":2,"description":"","link":"https:\/\/litci.org\/en\/tag\/world-war\/","name":"world war","slug":"world-war","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/litci.org\/en\/wp-json\/wp\/v2\/tags\/4432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/litci.org\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/litci.org\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/litci.org\/en\/wp-json\/wp\/v2\/posts?tags=4432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}